{"id":7018,"date":"2020-07-14T13:30:00","date_gmt":"2020-07-14T13:30:00","guid":{"rendered":"https:\/\/news.dream.press\/news\/?post_type=announcement&#038;p=7018"},"modified":"2024-11-15T03:02:30","modified_gmt":"2024-11-15T03:02:30","slug":"dreamhost-se-une-a-la-fundacion-mobilecoin","status":"publish","type":"announcement","link":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/dreamhost-se-une-a-la-fundacion-mobilecoin\/","title":{"rendered":"DreamHost se une a la fundaci\u00f3n MobileCoin"},"content":{"rendered":"<p>Hoy estamos felices de anunciar que DreamHost se ha unido a la fundaci\u00f3n MobileCoin.<\/p>\n<p><a href=\"https:\/\/www.mobilecoin.com\/\" rel=\"noreferrer noopener\" target=\"_blank\">MobileCoin<\/a> es una criptomoneda dise\u00f1ada desde cero con privacidad, estabilidad de precios y facilidad de uso en mente. La red de pago global de bajo costo de MobileCoin es clave para el \u00e9xito continuado de nuestra base de clientes globales que buscan una plataforma de pago econ\u00f3mica y f\u00e1cil de usar.<\/p>\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 son las criptomonedas?<\/h2>\n<p>En t\u00e9rminos simples, las criptomonedas son monedas digitales. Son sistemas de pago encriptados y descentralizados. Y hay muchas de ellas en el mercado. Probablemente has escuchado hablar de Bitcoin, la primera criptomoneda del mundo. En total, hay m\u00e1s de 6,000 monedas digitales en comercio hoy d\u00eda con nombres como Etherium, Dogecoin y Brettcoin, \u00a1solo por nombrar algunas!<\/p>\n<h2 class=\"wp-block-heading\">MobileCoin es f\u00e1cil de usar.<\/h2>\n<p>MobileCoin tiene como objetivo ser tan f\u00e1cil e intuitivo de usar como algunos de los sistemas de pago m\u00e1s <a href=\"https:\/\/www.dreamhost.com\/blog\/10-online-payment-gateways-compared\/\">populares<\/a>. Fue creado con facilidad de uso y un enfoque en la experiencia del usuario final en el coraz\u00f3n de cada decisi\u00f3n de dise\u00f1o.<\/p>\n<h2 class=\"wp-block-heading\">Es r\u00e1pido.<\/h2>\n<p>Tradicionalmente, la mayor\u00eda de las criptomonedas han sido muy dif\u00edciles de usar. Obst\u00e1culos t\u00e9cnicos \u2014 combinados con tiempos de transacci\u00f3n extremadamente largos que tardan horas (\u00a1o d\u00edas!) en completarse \u2014 han llevado a muchos entusiastas de las criptomonedas a tratarla como una inversi\u00f3n a largo plazo y no como una moneda gastable. Debido a algunas decisiones inteligentes de arquitectura, la mayor\u00eda de las transacciones de MobileCoin se completan en menos de 10 segundos.<\/p>\n<h2 class=\"wp-block-heading\">Es seguro.<\/h2>\n<p>MobileCoin est\u00e1 enfocado en la privacidad del usuario. Como su nombre indica, MobileCoin est\u00e1 dise\u00f1ado para ser una criptomoneda prioritariamente m\u00f3vil<br \/>\n  que se integra en aplicaciones de comunicaci\u00f3n segura como Signal y WhatsApp.<\/p>\n<h2 class=\"wp-block-heading\">Nuestra Participaci\u00f3n<\/h2>\n<p>DreamHost se enorgullece de ser un socio de lanzamiento de MobileCoin.<\/p>\n<p><a href=\"https:\/\/www.dreamhost.com\/blog\/celebrating-20-years-of-the-open-source-manifesto\/\">Siempre hemos adoptado<br \/>\n    proyectos de c\u00f3digo abierto<\/a> que ayudan a las personas a poseer su presencia digital, y MobileCoin cumple con todos los requisitos. Es<br \/>\n  una red de pagos global de bajo costo que ayuda a todos nuestros clientes, especialmente a nuestros clientes internacionales, a realizar<br \/>\n  transacciones comerciales de manera segura y protegida.<\/p>\n<p>DreamHost ser\u00e1 miembro inaugural de la Fundaci\u00f3n MobileCoin, y estaremos donando nuestro tiempo y recursos para operar<br \/>\n  varios nodos de procesamiento de MobileCoin, inteligentemente dise\u00f1ados y altamente encriptados, en nuestra red.<\/p>\n<p>Estos nodos son solo un primer paso. Continuaremos ofreciendo consejos y orientaci\u00f3n a trav\u00e9s de nuestro asiento en el Comit\u00e9 Asesor T\u00e9cnico de MobileCoin y estamos ansiosos por ver c\u00f3mo nuestros muchos clientes de peque\u00f1as empresas deciden aprovechar esta nueva tecnolog\u00eda de pago.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy estamos felices de anunciar que DreamHost se ha unido a la fundaci\u00f3n MobileCoin. MobileCoin\u00a0es una criptomoneda dise\u00f1ada desde cero con privacidad, estabilidad de precios y usabilidad en mente. La red de pago global de bajo costo de MobileCoin es clave para el \u00e9xito continuado de nuestra base de clientes global que busca una plataforma de pago econ\u00f3mica y f\u00e1cil de usar. \u00bfQu\u00e9 son las criptomonedas? Ponga [\u2026]<\/p>\n","protected":false},"author":3,"featured_media":3525,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_yoast_wpseo_metadesc":"","footnotes":""},"class_list":["post-7018","announcement","type-announcement","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DreamHost se une a la fundaci\u00f3n MobileCoin - DreamHost<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/dreamhost-se-une-a-la-fundacion-mobilecoin\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DreamHost se une a la fundaci\u00f3n MobileCoin - DreamHost\" \/>\n<meta property=\"og:description\" content=\"Hoy estamos felices de anunciar que DreamHost se ha unido a la fundaci\u00f3n MobileCoin. MobileCoin\u00a0es una criptomoneda dise\u00f1ada desde cero con privacidad, estabilidad de precios y usabilidad en mente. La red de pago global de bajo costo de MobileCoin es clave para el \u00e9xito continuado de nuestra base de clientes global que busca una plataforma de pago econ\u00f3mica y f\u00e1cil de usar. \u00bfQu\u00e9 son las criptomonedas? Ponga [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/dreamhost-se-une-a-la-fundacion-mobilecoin\/\" \/>\n<meta property=\"og:site_name\" content=\"DreamHost\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DreamHost\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-15T03:02:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dreamhost.com\/news\/wp-content\/uploads\/2023\/02\/DreamHost-Mobile-Coin-opt-750x498-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"498\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@dreamhost\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DreamHost se une a la fundaci\u00f3n MobileCoin - DreamHost","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/dreamhost-se-une-a-la-fundacion-mobilecoin\/","og_locale":"en_US","og_type":"article","og_title":"DreamHost se une a la fundaci\u00f3n MobileCoin - DreamHost","og_description":"Hoy estamos felices de anunciar que DreamHost se ha unido a la fundaci\u00f3n MobileCoin. MobileCoin\u00a0es una criptomoneda dise\u00f1ada desde cero con privacidad, estabilidad de precios y usabilidad en mente. La red de pago global de bajo costo de MobileCoin es clave para el \u00e9xito continuado de nuestra base de clientes global que busca una plataforma de pago econ\u00f3mica y f\u00e1cil de usar. \u00bfQu\u00e9 son las criptomonedas? Ponga [\u2026]","og_url":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/dreamhost-se-une-a-la-fundacion-mobilecoin\/","og_site_name":"DreamHost","article_publisher":"https:\/\/www.facebook.com\/DreamHost\/","article_modified_time":"2024-11-15T03:02:30+00:00","og_image":[{"width":750,"height":498,"url":"https:\/\/www.dreamhost.com\/news\/wp-content\/uploads\/2023\/02\/DreamHost-Mobile-Coin-opt-750x498-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@dreamhost","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/dreamhost-se-une-a-la-fundacion-mobilecoin\/#article","isPartOf":{"@id":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/dreamhost-se-une-a-la-fundacion-mobilecoin\/"},"author":{"name":"Brett Dunst","@id":"https:\/\/www.dreamhost.com\/news\/#\/schema\/person\/e6cb6238cacf6fb9a93789caf76dd93c"},"headline":"DreamHost se une a la fundaci\u00f3n MobileCoin","datePublished":"2020-07-14T13:30:00+00:00","dateModified":"2024-11-15T03:02:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/dreamhost-se-une-a-la-fundacion-mobilecoin\/"},"wordCount":463,"publisher":{"@id":"https:\/\/www.dreamhost.com\/news\/#organization"},"image":{"@id":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/dreamhost-se-une-a-la-fundacion-mobilecoin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dreamhost.com\/news\/wp-content\/uploads\/2023\/02\/DreamHost-Mobile-Coin-opt-750x498-1.jpg","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/dreamhost-se-une-a-la-fundacion-mobilecoin\/","url":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/dreamhost-se-une-a-la-fundacion-mobilecoin\/","name":"DreamHost se une a la fundaci\u00f3n MobileCoin - DreamHost","isPartOf":{"@id":"https:\/\/www.dreamhost.com\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/dreamhost-se-une-a-la-fundacion-mobilecoin\/#primaryimage"},"image":{"@id":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/dreamhost-se-une-a-la-fundacion-mobilecoin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dreamhost.com\/news\/wp-content\/uploads\/2023\/02\/DreamHost-Mobile-Coin-opt-750x498-1.jpg","datePublished":"2020-07-14T13:30:00+00:00","dateModified":"2024-11-15T03:02:30+00:00","breadcrumb":{"@id":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/dreamhost-se-une-a-la-fundacion-mobilecoin\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dreamhost.com\/news\/es\/anuncios\/dreamhost-se-une-a-la-fundacion-mobilecoin\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/dreamhost-se-une-a-la-fundacion-mobilecoin\/#primaryimage","url":"https:\/\/www.dreamhost.com\/news\/wp-content\/uploads\/2023\/02\/DreamHost-Mobile-Coin-opt-750x498-1.jpg","contentUrl":"https:\/\/www.dreamhost.com\/news\/wp-content\/uploads\/2023\/02\/DreamHost-Mobile-Coin-opt-750x498-1.jpg","width":750,"height":498,"caption":"DreamHost Joins MobileCoin Foundation thumbnail"},{"@type":"BreadcrumbList","@id":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/dreamhost-se-une-a-la-fundacion-mobilecoin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dreamhost.com\/news\/"},{"@type":"ListItem","position":2,"name":"Announcements","item":"https:\/\/www.dreamhost.com\/news\/announcements\/"},{"@type":"ListItem","position":3,"name":"DreamHost se une a la fundaci\u00f3n MobileCoin"}]},{"@type":"WebSite","@id":"https:\/\/www.dreamhost.com\/news\/#website","url":"https:\/\/www.dreamhost.com\/news\/","name":"DreamHost News","description":"Product announcements, events, and more.","publisher":{"@id":"https:\/\/www.dreamhost.com\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dreamhost.com\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.dreamhost.com\/news\/#organization","name":"DreamHost","url":"https:\/\/www.dreamhost.com\/news\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dreamhost.com\/news\/#\/schema\/logo\/image\/","url":"https:\/\/www.dreamhost.com\/news\/wp-content\/uploads\/2023\/03\/dreamhost-events.png","contentUrl":"https:\/\/www.dreamhost.com\/news\/wp-content\/uploads\/2023\/03\/dreamhost-events.png","width":1598,"height":921,"caption":"DreamHost"},"image":{"@id":"https:\/\/www.dreamhost.com\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DreamHost\/","https:\/\/x.com\/dreamhost"]},{"@type":"Person","@id":"https:\/\/www.dreamhost.com\/news\/#\/schema\/person\/e6cb6238cacf6fb9a93789caf76dd93c","name":"Brett Dunst","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c560b676913f01e3c4679f853ce85f3b1ffb2a92716cb7a56bc03cefb687020d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c560b676913f01e3c4679f853ce85f3b1ffb2a92716cb7a56bc03cefb687020d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c560b676913f01e3c4679f853ce85f3b1ffb2a92716cb7a56bc03cefb687020d?s=96&d=mm&r=g","caption":"Brett Dunst"},"description":"Brett's the VP of Corporate Communications at DreamHost and definitely not a robot. He tweets as @TremendousValue and it's not great.","sameAs":["https:\/\/www.dreamhost.com\/","https:\/\/x.com\/nikola.ivanov@dreamhost.com"],"url":"https:\/\/www.dreamhost.com\/news\/author\/brett\/"}]}},"lang":"es","translations":{"es":7018,"en":3524,"pt":7019,"pl":7020,"ru":7021,"de":7028,"uk":7031,"it":11716,"fr":12002,"nl":12018},"pll_sync_post":{},"_links":{"self":[{"href":"https:\/\/www.dreamhost.com\/news\/wp-json\/wp\/v2\/announcements\/7018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dreamhost.com\/news\/wp-json\/wp\/v2\/announcements"}],"about":[{"href":"https:\/\/www.dreamhost.com\/news\/wp-json\/wp\/v2\/types\/announcement"}],"author":[{"embeddable":true,"href":"https:\/\/www.dreamhost.com\/news\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/www.dreamhost.com\/news\/wp-json\/wp\/v2\/announcements\/7018\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dreamhost.com\/news\/wp-json\/wp\/v2\/media\/3525"}],"wp:attachment":[{"href":"https:\/\/www.dreamhost.com\/news\/wp-json\/wp\/v2\/media?parent=7018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}