{"id":14391,"date":"2025-10-08T06:00:00","date_gmt":"2025-10-08T13:00:00","guid":{"rendered":"https:\/\/news.dream.press\/news\/?post_type=announcement&#038;p=14391"},"modified":"2025-10-14T14:02:08","modified_gmt":"2025-10-14T21:02:08","slug":"certificacion-alianza-hosting-seguro","status":"publish","type":"announcement","link":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/certificacion-alianza-hosting-seguro\/","title":{"rendered":"\u00a1Estamos Certificados por la Alianza de Hosting Seguro!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Siempre hemos dicho que tus sitios web est\u00e1n seguros con nosotros, \u00a1pero ahora tenemos el certificado para demostrarlo!<\/p>\n\n\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/hostingsecurity.net\/verify?token=9e526dc959e544b7\"><img decoding=\"async\" width=\"616\" height=\"737\" data-src=\"https:\/\/www.dreamhost.com\/news\/wp-content\/uploads\/2025\/10\/SHA-Trust-Seal-Final-e1759781360791.png\" alt=\"Alianza de Hosting Seguro - Certificado\" class=\"wp-image-14322 lazyload\" style=\"--smush-placeholder-width: 616px; --smush-placeholder-aspect-ratio: 616\/737;width:126px;height:auto\" data-srcset=\"https:\/\/www.dreamhost.com\/news\/wp-content\/uploads\/2025\/10\/SHA-Trust-Seal-Final-e1759781360791.png 616w, https:\/\/www.dreamhost.com\/news\/wp-content\/uploads\/2025\/10\/SHA-Trust-Seal-Final-e1759781360791-251x300.png 251w, https:\/\/www.dreamhost.com\/news\/wp-content\/uploads\/2025\/10\/SHA-Trust-Seal-Final-e1759781360791-96x115.png 96w, https:\/\/www.dreamhost.com\/news\/wp-content\/uploads\/2025\/10\/SHA-Trust-Seal-Final-e1759781360791-192x230.png 192w, https:\/\/www.dreamhost.com\/news\/wp-content\/uploads\/2025\/10\/SHA-Trust-Seal-Final-e1759781360791-512x613.png 512w, https:\/\/www.dreamhost.com\/news\/wp-content\/uploads\/2025\/10\/SHA-Trust-Seal-Final-e1759781360791-460x550.png 460w\" data-sizes=\"(max-width: 616px) 100vw, 616px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/figure>\n\n\n<p class=\"wp-block-paragraph\">Me enorgullece anunciar que DreamHost ha sido oficialmente certificado por la <a href=\"https:\/\/hostingsecurity.net\/\">Secure Hosting Alliance<\/a> (SHA), una iniciativa de la industria que establece el est\u00e1ndar de excelencia operacional entre los miembros de la industria de hosting web.<\/p>\n\n\n<p class=\"wp-block-paragraph\">Las empresas de Hosting como DreamHost son un eslab\u00f3n clave en la cadena de entrega de contenido en l\u00ednea. Los hosts web que han sido certificados por SHA han cumplido con est\u00e1ndares rigurosos en torno a la protecci\u00f3n de datos, la fiabilidad operacional y la resiliencia de la infraestructura.<\/p>\n\n\n<h2 class=\"wp-block-heading\">DreamHost: Una Voz Fundadora para un Web M\u00e1s Seguro<\/h2>\n\n\n<p class=\"wp-block-paragraph\">No solo nos inscribimos en el programa. Nosotros ayudamos a <em>construirlo<\/em>.<\/p>\n\n\n<p class=\"wp-block-paragraph\">Como miembro fundador del programa de certificaci\u00f3n de la Alianza de Hosting Seguro, DreamHost tuvo una participaci\u00f3n en la definici\u00f3n de los requisitos de la certificaci\u00f3n desde el primer d\u00eda. Nuestro equipo trabaj\u00f3 junto a otros hosts web durante el \u00faltimo a\u00f1o para definir lo que realmente significa &#8220;hosting seguro&#8221; y para asegurarse de que esos est\u00e1ndares protejan tanto a los creadores web como a las comunidades a las que sirven.<\/p>\n\n\n<h2 class=\"wp-block-heading\">Por Qu\u00e9 Es Importante<\/h2>\n\n\n<p class=\"wp-block-paragraph\">Nuestros clientes conf\u00edan en nosotros con sus sitios web, sus datos privados y su informaci\u00f3n personal. Mantener esos datos seguros es una responsabilidad que nunca hemos tomado a la ligera. Siempre hemos puesto la seguridad y el respeto por los datos de nuestros clientes en el n\u00facleo de nuestras operaciones, y esta certificaci\u00f3n valida la confianza que nuestros clientes han depositado en nosotros desde el principio.<\/p>\n\n\n<h2 class=\"wp-block-heading\">Construyendo Un Internet M\u00e1s Seguro, Juntos<\/h2>\n\n\n<p class=\"wp-block-paragraph\">Obtener la certificaci\u00f3n de la SHA no se trata solo de derechos de alardear. Se trata de demostrar nuestro compromiso con la construcci\u00f3n de una web m\u00e1s segura, confiable y responsable para todos.<\/p>\n\n\n<p class=\"wp-block-paragraph\">\u00a1As\u00ed que aqu\u00ed estamos para mantener tus sitios web seguros, tus datos intactos, y tus sue\u00f1os&#8230; alojados!<\/p>\n\n\n<p class=\"wp-block-paragraph\">Para m\u00e1s informaci\u00f3n sobre el programa de certificaci\u00f3n de la Alianza de Hosting Seguro, visita <a href=\"https:\/\/hostingsecurity.net\/trust-seal\/\">https:\/\/hostingsecurity.net\/trust-seal\/<\/a>.<\/p>\n\n\n<p class=\"wp-block-paragraph\">Y gracias, como siempre, por confiar en DreamHost con tu rinc\u00f3n en la web.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siempre hemos dicho que tus sitios web est\u00e1n seguros con nosotros, \u00a1pero ahora tenemos el certificado para demostrarlo! Estoy orgulloso de anunciar que DreamHost ha sido oficialmente certificado por la Secure Hosting Alliance (SHA), una iniciativa de la industria que establece el est\u00e1ndar de excelencia operacional entre los miembros de la industria de hosting. Compa\u00f1\u00edas de hosting como [\u2026]<\/p>\n","protected":false},"author":3,"featured_media":14320,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_yoast_wpseo_metadesc":"DreamHost obtiene la certificaci\u00f3n de la Alianza del Hosting Seguro: cumplimiento, mejores pr\u00e1cticas y protecci\u00f3n reforzada para tu web.","footnotes":""},"class_list":["post-14391","announcement","type-announcement","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1Estamos Certificados por la Alianza de Hosting Seguro! - DreamHost<\/title>\n<meta name=\"description\" content=\"DreamHost obtiene la certificaci\u00f3n de la Alianza del Hosting Seguro: cumplimiento, mejores pr\u00e1cticas y protecci\u00f3n reforzada para tu web.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/certificacion-alianza-hosting-seguro\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Estamos Certificados por la Alianza de Hosting Seguro! - DreamHost\" \/>\n<meta property=\"og:description\" content=\"DreamHost obtiene la certificaci\u00f3n de la Alianza del Hosting Seguro: cumplimiento, mejores pr\u00e1cticas y protecci\u00f3n reforzada para tu web.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/certificacion-alianza-hosting-seguro\/\" \/>\n<meta property=\"og:site_name\" content=\"DreamHost\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DreamHost\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-14T21:02:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dreamhost.com\/news\/wp-content\/uploads\/2025\/10\/SHA-Certification.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1364\" \/>\n\t<meta property=\"og:image:height\" content=\"866\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@dreamhost\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Estamos Certificados por la Alianza de Hosting Seguro! - DreamHost","description":"DreamHost obtiene la certificaci\u00f3n de la Alianza del Hosting Seguro: cumplimiento, mejores pr\u00e1cticas y protecci\u00f3n reforzada para tu web.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/certificacion-alianza-hosting-seguro\/","og_locale":"en_US","og_type":"article","og_title":"\u00a1Estamos Certificados por la Alianza de Hosting Seguro! - DreamHost","og_description":"DreamHost obtiene la certificaci\u00f3n de la Alianza del Hosting Seguro: cumplimiento, mejores pr\u00e1cticas y protecci\u00f3n reforzada para tu web.","og_url":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/certificacion-alianza-hosting-seguro\/","og_site_name":"DreamHost","article_publisher":"https:\/\/www.facebook.com\/DreamHost\/","article_modified_time":"2025-10-14T21:02:08+00:00","og_image":[{"width":1364,"height":866,"url":"https:\/\/www.dreamhost.com\/news\/wp-content\/uploads\/2025\/10\/SHA-Certification.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@dreamhost","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/certificacion-alianza-hosting-seguro\/#article","isPartOf":{"@id":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/certificacion-alianza-hosting-seguro\/"},"author":{"name":"Brett Dunst","@id":"https:\/\/www.dreamhost.com\/news\/#\/schema\/person\/e6cb6238cacf6fb9a93789caf76dd93c"},"headline":"\u00a1Estamos Certificados por la Alianza de Hosting Seguro!","datePublished":"2025-10-08T13:00:00+00:00","dateModified":"2025-10-14T21:02:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/certificacion-alianza-hosting-seguro\/"},"wordCount":388,"publisher":{"@id":"https:\/\/www.dreamhost.com\/news\/#organization"},"image":{"@id":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/certificacion-alianza-hosting-seguro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dreamhost.com\/news\/wp-content\/uploads\/2025\/10\/SHA-Certification.png","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/certificacion-alianza-hosting-seguro\/","url":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/certificacion-alianza-hosting-seguro\/","name":"\u00a1Estamos Certificados por la Alianza de Hosting Seguro! - DreamHost","isPartOf":{"@id":"https:\/\/www.dreamhost.com\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/certificacion-alianza-hosting-seguro\/#primaryimage"},"image":{"@id":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/certificacion-alianza-hosting-seguro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dreamhost.com\/news\/wp-content\/uploads\/2025\/10\/SHA-Certification.png","datePublished":"2025-10-08T13:00:00+00:00","dateModified":"2025-10-14T21:02:08+00:00","description":"DreamHost obtiene la certificaci\u00f3n de la Alianza del Hosting Seguro: cumplimiento, mejores pr\u00e1cticas y protecci\u00f3n reforzada para tu web.","breadcrumb":{"@id":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/certificacion-alianza-hosting-seguro\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dreamhost.com\/news\/es\/anuncios\/certificacion-alianza-hosting-seguro\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/certificacion-alianza-hosting-seguro\/#primaryimage","url":"https:\/\/www.dreamhost.com\/news\/wp-content\/uploads\/2025\/10\/SHA-Certification.png","contentUrl":"https:\/\/www.dreamhost.com\/news\/wp-content\/uploads\/2025\/10\/SHA-Certification.png","width":1364,"height":866,"caption":"Secure Hosting Alliance Certified - DreamHost"},{"@type":"BreadcrumbList","@id":"https:\/\/www.dreamhost.com\/news\/es\/anuncios\/certificacion-alianza-hosting-seguro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dreamhost.com\/news\/"},{"@type":"ListItem","position":2,"name":"Announcements","item":"https:\/\/www.dreamhost.com\/news\/announcements\/"},{"@type":"ListItem","position":3,"name":"\u00a1Estamos Certificados por la Alianza de Hosting Seguro!"}]},{"@type":"WebSite","@id":"https:\/\/www.dreamhost.com\/news\/#website","url":"https:\/\/www.dreamhost.com\/news\/","name":"DreamHost News","description":"Product announcements, events, and more.","publisher":{"@id":"https:\/\/www.dreamhost.com\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dreamhost.com\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.dreamhost.com\/news\/#organization","name":"DreamHost","url":"https:\/\/www.dreamhost.com\/news\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dreamhost.com\/news\/#\/schema\/logo\/image\/","url":"https:\/\/www.dreamhost.com\/news\/wp-content\/uploads\/2023\/03\/dreamhost-events.png","contentUrl":"https:\/\/www.dreamhost.com\/news\/wp-content\/uploads\/2023\/03\/dreamhost-events.png","width":1598,"height":921,"caption":"DreamHost"},"image":{"@id":"https:\/\/www.dreamhost.com\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DreamHost\/","https:\/\/x.com\/dreamhost"]},{"@type":"Person","@id":"https:\/\/www.dreamhost.com\/news\/#\/schema\/person\/e6cb6238cacf6fb9a93789caf76dd93c","name":"Brett Dunst","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c560b676913f01e3c4679f853ce85f3b1ffb2a92716cb7a56bc03cefb687020d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c560b676913f01e3c4679f853ce85f3b1ffb2a92716cb7a56bc03cefb687020d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c560b676913f01e3c4679f853ce85f3b1ffb2a92716cb7a56bc03cefb687020d?s=96&d=mm&r=g","caption":"Brett Dunst"},"description":"Brett's the VP of Corporate Communications at DreamHost and definitely not a robot. He tweets as @TremendousValue and it's not great.","sameAs":["https:\/\/www.dreamhost.com\/","https:\/\/x.com\/nikola.ivanov@dreamhost.com"],"url":"https:\/\/www.dreamhost.com\/news\/author\/brett\/"}]}},"lang":"es","translations":{"es":14391,"ru":14371,"en":14314,"uk":14372,"de":14397,"fr":14425,"pt":14431,"pl":14432,"nl":14450,"it":14463},"pll_sync_post":{},"_links":{"self":[{"href":"https:\/\/www.dreamhost.com\/news\/wp-json\/wp\/v2\/announcements\/14391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dreamhost.com\/news\/wp-json\/wp\/v2\/announcements"}],"about":[{"href":"https:\/\/www.dreamhost.com\/news\/wp-json\/wp\/v2\/types\/announcement"}],"author":[{"embeddable":true,"href":"https:\/\/www.dreamhost.com\/news\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/www.dreamhost.com\/news\/wp-json\/wp\/v2\/announcements\/14391\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dreamhost.com\/news\/wp-json\/wp\/v2\/media\/14320"}],"wp:attachment":[{"href":"https:\/\/www.dreamhost.com\/news\/wp-json\/wp\/v2\/media?parent=14391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}