{"id":40443,"date":"2023-05-16T08:07:39","date_gmt":"2023-05-16T15:07:39","guid":{"rendered":"https:\/\/dhblog.dream.press\/blog\/?p=40443"},"modified":"2025-01-16T14:42:32","modified_gmt":"2025-01-16T22:42:32","slug":"reportes-ga4-guia-adquisicion-conversiones","status":"publish","type":"post","link":"https:\/\/www.dreamhost.com\/blog\/es\/reportes-ga4-guia-adquisicion-conversiones\/","title":{"rendered":"Reportes GA4: La Gu\u00eda Completa sobre Adquisici\u00f3n, Conversiones y M\u00e1s"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Antes de GA4, hab\u00eda\u2026<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">\u2026 UA\u2026<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Y, antes de UA, hab\u00eda\u2026<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">\u2026 GA\u2026<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Y, antes de GA, hab\u00eda\u2026.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">\u2026 \u00bfUrchin?<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Bueno\u2026 Hablando en serio, no sabemos qui\u00e9n est\u00e1 a cargo de darle nombre a las cosas en Google. Pero aqu\u00ed estamos.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Google Analytics 4 (GA4) es una gran herramienta para analizar el rendimiento de sitios web y aplicaciones.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.dreamhost.com\/blog\/es\/cambio-de-universal-analytics-a-ga4\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">GA4 est\u00e1 destinado a reemplazar Universal Analytics<\/span><\/a><span style=\"font-weight: 400;\">, el cual es la generaci\u00f3n actual del software de Google Analytics. Un <\/span><a href=\"https:\/\/w3techs.com\/technologies\/details\/ta-googleanalytics\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">86% de los sitios web en el Internet lo usan y cuentan con herramientas de an\u00e1lisis de tr\u00e1fico<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">En el mundo del marketing digital, esto es como cuando lanzan el nuevo modelo de tu auto favorito y la respuesta se divide. Algunos lo aman. Algunos lo odian.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Pero todos vamos a tener que probarlo, porque UA est\u00e1 programado para apagarse en Julio de 2023. Luego, GA4 lo reemplazar\u00e1 permanentemente.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">En esta gu\u00eda, profundizaremos en los informes de GA4 \u2014 hablando de m\u00e9tricas, conversiones, visualizaciones y m\u00e1s.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Entender c\u00f3mo dominar la pesta\u00f1a \u2018Informes\u2019 en GA4 es esencial, si trabajas con campa\u00f1as de marketing, SEO, administraci\u00f3n de sitios web, retenci\u00f3n, comercio electr\u00f3nico, o cualquier otra cosa que implique rastreos.<\/span><\/p>\n\n\n\n<h2 id=\"h-entendiendo-la-pestana-de-informes-de-ga4\" class=\"wp-block-heading\"><strong><a id=\"entender\"><\/a>Entendiendo la Pesta\u00f1a de Informes de GA4<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">En primer lugar, ubiqu\u00e9monos.<\/span><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"900\" height=\"404\" data-src=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Pestana-informes-GA4.jpg.webp\" alt=\"ubicando la pesta\u00f1a de Informes en GA4.\" class=\"wp-image-40445 lazyload\" data-srcset=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Pestana-informes-GA4.jpg.webp 900w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/Pestana-informes-GA4-300x135.jpg 300w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/Pestana-informes-GA4-768x345.jpg 768w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Pestana-informes-GA4-600x269.jpg.webp 600w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Pestana-informes-GA4-730x328.jpg.webp 730w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Pestana-informes-GA4-784x352.jpg.webp 784w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Pestana-informes-GA4-877x394.jpg.webp 877w\" data-sizes=\"(max-width: 900px) 100vw, 900px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 900px; --smush-placeholder-aspect-ratio: 900\/404;\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">La pesta\u00f1a de Informes de GA4 es el centro principal para acceder y analizar datos en una propiedad GA4.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Los siguientes son los informes disponibles en GA4:<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">Vista general de informes<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">En tiempo real (Realtime)<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Adquisici\u00f3n<\/span>\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">Resumen<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Adquisici\u00f3n de usuarios<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Adquisici\u00f3n de tr\u00e1fico<\/span><\/li>\n\n\n\n\n<\/ul>\n\n\n\n\n<\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Interacci\u00f3n<\/span>\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">Resumen<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Eventos<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Conversiones<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">P\u00e1ginas y pantallas<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">P\u00e1gina de destino<\/span><\/li>\n\n\n\n\n<\/ul>\n\n\n\n\n<\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Monetizaci\u00f3n<\/span>\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">Compras de comercio electr\u00f3nico<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Compras de aplicaciones<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Anuncios de editores<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Promociones<\/span><\/li>\n\n\n\n\n<\/ul>\n\n\n\n\n<\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Retenci\u00f3n<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Demograf\u00eda<\/span>\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">Resumen<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Detalles demogr\u00e1ficos<\/span><\/li>\n\n\n\n\n<\/ul>\n\n\n\n\n<\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Tecnolog\u00eda<\/span>\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">Resumen<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Detalles de tecnolog\u00eda<\/span><\/li>\n\n\n\n\n<\/ul>\n\n\n\n\n<\/li>\n\n\n\n\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">En esta gu\u00eda, veremos cada secci\u00f3n y exploraremos c\u00f3mo puedes usar los datos para informar campa\u00f1as de marketing, gastos publicitarios y m\u00e1s.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Antes de ahondar m\u00e1s, recuerda que puedes dividir todos los informes en dos tipos principales:<\/span><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><b>Informes de Vista General<\/b><span style=\"font-weight: 400;\">: Son res\u00famenes de alto nivel, de m\u00e9tricas clave (como adquisici\u00f3n de usuario, tasa de compromiso y recuento de eventos).<\/span><\/li>\n\n\n\n<li><b>Informes detallados<\/b><span style=\"font-weight: 400;\">: Mide dimensiones y m\u00e9tricas espec\u00edficas, para un an\u00e1lisis detallado (como demograf\u00eda, categor\u00eda de dispositivo, nombre del evento).<\/span><\/li>\n\n\n\n\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">GA4 tambi\u00e9n ofrece algunas caracter\u00edsticas de informe nuevas, como la exploraci\u00f3n de rutas y los informes de exploraci\u00f3n, pero ya luego cubriremos eso, en una gu\u00eda separada.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Para este art\u00edculo, iremos directamente a la lista de informes del men\u00fa de la izquierda.<\/span><\/p>\n\n\n\n<div class=\"article-newsletter article-newsletter--gradient\">\n\n\n<h2>Get Content Delivered Straight to Your Inbox<\/h2><p>Subscribe now to receive all the latest updates, delivered directly to your inbox.<\/p><form class=\"nwsl-form\" id=\"newsletter_block_\" novalidate><div class=\"messages\"><\/div><div class=\"form-group\"><label for=\"input_newsletter_block_\"><input type=\"email\"name=\"email\"id=\"input_newsletter_block_\"placeholder=\"Enter your email address\"novalidatedisabled=\"disabled\"\/><\/label><button type=\"submit\"class=\"btn btn--brand\"disabled=\"disabled\"><span>Sign Me Up!<\/span><svg width=\"21\" height=\"14\" viewBox=\"0 0 21 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M13.8523 0.42524L12.9323 1.34521C12.7095 1.56801 12.7132 1.9304 12.9404 2.14865L16.7241 5.7823H0.5625C0.251859 5.7823 0 6.03416 0 6.3448V7.6573C0 7.96794 0.251859 8.2198 0.5625 8.2198H16.7241L12.9405 11.8535C12.7132 12.0717 12.7095 12.4341 12.9323 12.6569L13.8523 13.5769C14.072 13.7965 14.4281 13.7965 14.6478 13.5769L20.8259 7.39879C21.0456 7.17913 21.0456 6.82298 20.8259 6.60327L14.6477 0.42524C14.4281 0.205584 14.0719 0.205584 13.8523 0.42524Z\" fill=\"white\"\/>\n<\/svg>\n<\/button><\/div><\/form><\/div>\n\n\n<h2 id=\"h-informe-panoramico\" class=\"wp-block-heading\"><strong><a id=\"panoramico\"><\/a>Informe Panor\u00e1mico<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Si buscas entender c\u00f3mo funciona tu sitio, ve directamente al Informe Panor\u00e1mico.<\/span><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"900\" height=\"392\" data-src=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/informe-panoramico-GA4.jpg.webp\" alt=\"Conociendo el Informe Panor\u00e1mico de GA4.\" class=\"wp-image-40446 lazyload\" data-srcset=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/informe-panoramico-GA4.jpg.webp 900w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/informe-panoramico-GA4-300x131.jpg 300w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/informe-panoramico-GA4-768x335.jpg 768w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/informe-panoramico-GA4-600x261.jpg.webp 600w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/informe-panoramico-GA4-730x318.jpg.webp 730w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/informe-panoramico-GA4-784x341.jpg.webp 784w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/informe-panoramico-GA4-877x382.jpg.webp 877w\" data-sizes=\"(max-width: 900px) 100vw, 900px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 900px; --smush-placeholder-aspect-ratio: 900\/392;\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Este Informe es, en pocas palabras, un panel de an\u00e1lisis pre construido.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Mezcla los datos de todos tus dem\u00e1s informes en una sola vista. As\u00ed, tendr\u00e1s una visi\u00f3n m\u00e1s general de cu\u00e1nto tr\u00e1fico recibes, de d\u00f3nde viene y qu\u00e9 acciones toman los usuarios en tu sitio.<\/span><\/p>\n\n\n\n<h2 id=\"h-informes-en-tiempo-real-en-ga4\" class=\"wp-block-heading\"><strong><a id=\"tiempo\"><\/a>Informes en Tiempo Real en GA4<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Estos informes de GA4 funcionan casi del mismo modo que en Universal Analytics. Obtendr\u00e1s una visi\u00f3n en tiempo real de tus visitantes, durante los \u00faltimos 30 minutos.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Ver\u00e1s datos clave como:<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">Usuarios activos<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">P\u00e1ginas m\u00e1s activas<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Eventos principales<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Datos geogr\u00e1ficos<\/span><\/li>\n\n\n\n\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Los informes en tiempo real son una forma genial de ver lo que pasa en tu p\u00e1gina, justo ahora. Pero si quieres ir m\u00e1s profundo en el an\u00e1lisis y entender el comportamiento de uno de tus visitantes a lo largo de su ciclo de vida, o deseas comparar m\u00e9tricas, en diferentes rangos de fechas, necesitar\u00e1s indagar en los informes relevantes que te mostraremos a continuaci\u00f3n.<\/span><\/p>\n\n\n\n<h2 id=\"h-informes-de-adquisicion\" class=\"wp-block-heading\"><strong><a id=\"adquisicion\"><\/a>Informes de Adquisici\u00f3n<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">La adquisici\u00f3n se trata de entender c\u00f3mo los usuarios llegaron a tu sitio web.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Dentro de la secci\u00f3n Adquisici\u00f3n, ver\u00e1s 3 informes diferentes.&nbsp;<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-resumen-de-la-adquisicion\"><strong>1. Resumen de la Adquisici\u00f3n<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">El informe de Resumen es como el informe anterior, pero se centra en m\u00e9tricas que tienen que ver solo con adquisici\u00f3n. Ver\u00e1s una combinaci\u00f3n de datos sobre c\u00f3mo los usuarios encuentran tu sitio web, adem\u00e1s de los canales o campa\u00f1as que generan un mayor tr\u00e1fico.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-adquisicion-de-usuarios\"><strong>2. Adquisici\u00f3n de Usuarios<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">El informe de Adquisici\u00f3n de Usuarios filtrar\u00e1 tu tr\u00e1fico, para ver solamente c\u00f3mo llegan nuevos usuarios a tu sitio por primera vez. Es muy \u00fatil para comprender mejor c\u00f3mo la gente descubre tu sitio web. Adem\u00e1s, te ayudar\u00e1 con la atribuci\u00f3n de marketing digital.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">B\u00e1sicamente: <\/span><b>\u00bfC\u00f3mo la gente encontr\u00f3 tu sitio web en primer lugar?<\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Por ejemplo, puedes preguntarte: \u00bfSon m\u00e1s quienes llegan a mi sitio por Instagram y luego hacen clic en el anuncio? \u00bfO los que hacen clic y luego nos encuentran por Instagram?<\/span><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"900\" height=\"349\" data-src=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-adquisicion-usuarios-GA4.jpg.webp\" alt=\"Conociendo el Informe Adquisici\u00f3n de Usuarios.\" class=\"wp-image-40447 lazyload\" data-srcset=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-adquisicion-usuarios-GA4.jpg.webp 900w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/Informe-adquisicion-usuarios-GA4-300x116.jpg 300w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/Informe-adquisicion-usuarios-GA4-768x298.jpg 768w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-adquisicion-usuarios-GA4-600x233.jpg.webp 600w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-adquisicion-usuarios-GA4-730x283.jpg.webp 730w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-adquisicion-usuarios-GA4-784x304.jpg.webp 784w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-adquisicion-usuarios-GA4-877x340.jpg.webp 877w\" data-sizes=\"(max-width: 900px) 100vw, 900px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 900px; --smush-placeholder-aspect-ratio: 900\/349;\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">La vista predeterminada del informe de Adquisici\u00f3n de Usuarios te ayudar\u00e1 a responder esa pregunta, pues te muestra la Primera interacci\u00f3n del Usuario, por grupo de canales por defecto.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Tambi\u00e9n puedes alternar este informe, haciendo clic en el men\u00fa desplegable y agrupando la adquisici\u00f3n por otras dimensiones que desees, como Origen, Medio o Campa\u00f1a.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-adquisicion-de-trafico\"><strong>3. Adquisici\u00f3n de Tr\u00e1fico<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Este informe muestra muchos de los datos que el informe anterior, pero no filtra en orden para mostrar solo a los nuevos usuarios. En su lugar, te permite ver el origen o el canal que gener\u00f3 tr\u00e1fico a tu sitio web, independientemente de si es la primera o la cent\u00e9sima visita del usuario.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">El grupo predeterminado de canales dividir\u00e1 tu tr\u00e1fico en contenedores, como tr\u00e1fico de referencia de otros sitios web, tr\u00e1fico org\u00e1nico de motores de b\u00fasqueda, anuncios pagos de b\u00fasqueda, marketing por correo electr\u00f3nico y otros contenedores comunes.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">\n\n\n\n<div class=\"glossary-term\">\n\t<a\n\t\tclass=\"glossary-term__above-title\"\n\t\thref=\"\"\n\t\ttarget=\"_blank\"\n\t\trel=\"noopener noreferrer\"\n\t>\n\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\"><path d=\"M320 32c-8.1 0-16.1 1.4-23.7 4.1L15.8 137.4C6.3 140.9 0 149.9 0 160s6.3 19.1 15.8 22.6l57.9 20.9C57.3 229.3 48 259.8 48 291.9v28.1c0 28.4-10.8 57.7-22.3 80.8c-6.5 13-13.9 25.8-22.5 37.6C0 442.7-.9 448.3 .9 453.4s6 8.9 11.2 10.2l64 16c4.2 1.1 8.7 .3 12.4-2s6.3-6.1 7.1-10.4c8.6-42.8 4.3-81.2-2.1-108.7C90.3 344.3 86 329.8 80 316.5V291.9c0-30.2 10.2-58.7 27.9-81.5c12.9-15.5 29.6-28 49.2-35.7l157-61.7c8.2-3.2 17.5 .8 20.7 9s-.8 17.5-9 20.7l-157 61.7c-12.4 4.9-23.3 12.4-32.2 21.6l159.6 57.6c7.6 2.7 15.6 4.1 23.7 4.1s16.1-1.4 23.7-4.1L624.2 182.6c9.5-3.4 15.8-12.5 15.8-22.6s-6.3-19.1-15.8-22.6L343.7 36.1C336.1 33.4 328.1 32 320 32zM128 408c0 35.3 86 72 192 72s192-36.7 192-72L496.7 262.6 354.5 314c-11.1 4-22.8 6-34.5 6s-23.5-2-34.5-6L143.3 262.6 128 408z\"\/><\/svg>\n\t\t<span><\/span>\n\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 384 512\"><path d=\"M342.6 233.4c12.5 12.5 12.5 32.8 0 45.3l-192 192c-12.5 12.5-32.8 12.5-45.3 0s-12.5-32.8 0-45.3L274.7 256 105.4 86.6c-12.5-12.5-12.5-32.8 0-45.3s32.8-12.5 45.3 0l192 192z\"\/><\/svg>\n\t<\/a>\n    <h3>B\u00fasqueda Org\u00e1nica<\/h3>\n    <p>Las b\u00fasquedas org\u00e1nicas describen los resultados no pagados en las P\u00e1ginas de Resultados de Motores de B\u00fasqueda (SERPs). Estos se clasifican solo por el algoritmo de un motor de b\u00fasqueda.<\/p>\n    \n<\/div>\n\n<\/span><\/p>\n\n\n\n<h2 id=\"h-informes-de-interaccion\" class=\"wp-block-heading\"><strong><a id=\"interaccion\"><\/a>Informes de Interacci\u00f3n<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Ahora ya sabes de d\u00f3nde viene el tr\u00e1fico. \u00bfPero qu\u00e9 hacen al llegar a tu sitio web?&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">De eso se tratan los Informes de Interacci\u00f3n.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Esta informaci\u00f3n te ayudar\u00e1 a responder preguntas claves, como:<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">\u00bfCu\u00e1l fue el contenido m\u00e1s popular en tu sitio web?<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">\u00bfEn cu\u00e1les enlaces hicieron clic m\u00e1s veces los usuarios?<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">\u00bfCu\u00e1ntos usuarios completaron metas o compras?<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">\u00bfCu\u00e1les p\u00e1ginas llevaron a la gente al sitio web en primer lugar?<\/span><\/li>\n\n\n\n\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">B\u00e1sicamente, estamos a punto de convertir esta reuni\u00f3n de an\u00e1lisis en una fiesta de an\u00e1lisis.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-resumen\"><strong>1. Resumen<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Como se esperaba, el Resumen presenta los datos que se mostrar\u00e1n a continuaci\u00f3n.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Aqu\u00ed ver\u00e1s un resumen de alto nivel, de cada detalle que habr\u00e1 en los informes subsecuentes.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-informe-de-eventos\"><strong>2. Informe de Eventos<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">El informe de Eventos es donde ocurre la magia. <\/span><span style=\"font-weight: 400;\"><br><\/span><span style=\"font-weight: 400;\"><br><\/span><span style=\"font-weight: 400;\">Aqu\u00ed ver\u00e1s datos detallados sobre las acciones que realizan los visitantes de tu sitio.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">De forma predeterminada, ver\u00e1s conceptos como <\/span><b>page_view<\/b><span style=\"font-weight: 400;\">, <\/span><b>scroll<\/b><span style=\"font-weight: 400;\">, <\/span><b>click<\/b><span style=\"font-weight: 400;\">, <\/span><b>first_visit<\/b><span style=\"font-weight: 400;\">, <\/span><span style=\"font-weight: 400;\">y m\u00e1s.<\/span><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"900\" height=\"614\" data-src=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-eventos-GA4.jpg.webp\" alt=\"Conociendo el Informe de Eventos.\" class=\"wp-image-40448 lazyload\" data-srcset=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-eventos-GA4.jpg.webp 900w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/Informe-eventos-GA4-300x205.jpg 300w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/Informe-eventos-GA4-768x524.jpg 768w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-eventos-GA4-600x409.jpg.webp 600w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-eventos-GA4-730x498.jpg.webp 730w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-eventos-GA4-784x535.jpg.webp 784w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-eventos-GA4-877x598.jpg.webp 877w\" data-sizes=\"(max-width: 900px) 100vw, 900px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 900px; --smush-placeholder-aspect-ratio: 900\/614;\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">(Las \u201cVistas de P\u00e1gina\u201d se consideran un evento en GA4.)<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Puedes crear hasta <\/span><a href=\"https:\/\/www.dreamhost.com\/blog\/es\/guia-creacion-medicion-eventos-ga4\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">eventos personalizados de GA4<\/span><\/a><span style=\"font-weight: 400;\">, para rastrear cosas como registros, suscripciones, u otras acciones.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Si haces clic en cada evento, puedes profundizar m\u00e1s para ver m\u00e1s informaci\u00f3n sobre las acciones, cu\u00e1ndo y d\u00f3nde ocurrieron y otros detalles.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-informe-de-conversiones\"><strong>3. Informe de Conversiones<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Adem\u00e1s de todos los eventos de tu sitio web, puede que algunas de estas acciones representen una conversi\u00f3n real, correlacionada con ventas o ingresos.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Por ejemplo, cuando un usuario crea una cuenta, o cuando compra algo.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Indica, al configurar eventos GA4, si cada evento en espec\u00edfico debe ser tratado como una conversi\u00f3n. Si lo haces, esos eventos aparecer\u00e1n en este informe especial.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Esto filtrar\u00e1 las conversiones que se han completado. Podr\u00e1s, adem\u00e1s, profundizar, para ver de d\u00f3nde proviene cada conversi\u00f3n, entre otros datos relevantes.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">(Nota nerd: En GA4, los eventos marcados como Conversiones han reemplazado completamente a los \u201cObjetivos\u201d.)<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-paginas-y-pantallas\"><strong>4. P\u00e1ginas y Pantallas<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Este informe luce como el conocido informe \u201cVistas de p\u00e1gina\u201d de Universal Analytics.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Aqu\u00ed, podr\u00e1s ver r\u00e1pidamente cu\u00e1les p\u00e1ginas de tu sitio web acumulan m\u00e1s vistas, han sido visitadas por una mayor cantidad de usuarios, y han aportado m\u00e1s conversiones.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">El informe predeterminado mostrar\u00e1 las p\u00e1ginas por su t\u00edtulo, pero si est\u00e1s acostumbrado a navegar por p\u00e1ginas usando sus URL, podr\u00e1s cambiar la vista desde el men\u00fa desplegable, sobre la lista de p\u00e1ginas.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-5-paginas-de-destino\"><strong>5. P\u00e1ginas de Destino<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Las p\u00e1ginas de destino son las primeras que un usuario ve, al llegar a tu sitio web. Es como si tuvieras una casa enorme, con docenas o cientos (hasta miles) de puertas principales. Siempre es bueno saber cu\u00e1les emplean m\u00e1s tus invitados.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">(Obviamente, con una casa tan grande, tus invitados entrar\u00e1n y saldr\u00e1n constantemente).<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Entonces, el informe de P\u00e1ginas de Destino indica cu\u00e1l(es) puerta(s) usa(n) m\u00e1s tus visitantes.&nbsp;<\/span><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"900\" height=\"462\" data-src=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Reporte-paginas-destino.jpg.webp\" alt=\"Conociendo el Informe de P\u00e1ginas de Destino.\" class=\"wp-image-40449 lazyload\" data-srcset=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Reporte-paginas-destino.jpg.webp 900w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/Reporte-paginas-destino-300x154.jpg 300w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/Reporte-paginas-destino-768x394.jpg 768w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Reporte-paginas-destino-600x308.jpg.webp 600w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Reporte-paginas-destino-730x375.jpg.webp 730w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Reporte-paginas-destino-784x402.jpg.webp 784w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Reporte-paginas-destino-877x450.jpg.webp 877w\" data-sizes=\"(max-width: 900px) 100vw, 900px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 900px; --smush-placeholder-aspect-ratio: 900\/462;\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">As\u00ed podr\u00e1s hacerte una idea de cu\u00e1les p\u00e1ginas o contenidos son m\u00e1s atractivos para tus usuarios, obteniendo la mayor visibilidad en los resultados de b\u00fasqueda org\u00e1nica, o generando un mayor revuelo en las redes sociales.<\/span><\/p>\n\n\n\n<h2 id=\"h-informes-de-monetizacion\" class=\"wp-block-heading\"><strong><a id=\"monetizacion\"><\/a>Informes de Monetizaci\u00f3n<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Como podr\u00e1s suponer por su nombre, los informes de Monetizaci\u00f3n existen para ayudarte a comprender c\u00f3mo genera ingresos tu sitio y cu\u00e1les son sus p\u00e1ginas m\u00e1s demandadas.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-resumen-0\"><strong>1. Resumen<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Obt\u00e9n una vista general de los ingresos que genera tu sitio, sus ventas realizadas, el valor promedio de compras de tus visitantes y mucho m\u00e1s, en el Resumen de Monetizaci\u00f3n.<\/span><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"900\" height=\"407\" data-src=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Reporte-general-monetizacion-GA4.jpg.webp\" alt=\"Conociendo el Informe de Resumen de Monetizaci\u00f3n.\" class=\"wp-image-40450 lazyload\" data-srcset=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Reporte-general-monetizacion-GA4.jpg.webp 900w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/Reporte-general-monetizacion-GA4-300x136.jpg 300w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/Reporte-general-monetizacion-GA4-768x347.jpg 768w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Reporte-general-monetizacion-GA4-600x271.jpg.webp 600w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Reporte-general-monetizacion-GA4-730x330.jpg.webp 730w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Reporte-general-monetizacion-GA4-784x355.jpg.webp 784w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Reporte-general-monetizacion-GA4-877x397.jpg.webp 877w\" data-sizes=\"(max-width: 900px) 100vw, 900px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 900px; --smush-placeholder-aspect-ratio: 900\/407;\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-compras-de-comercio-electronico\"><strong>2. Compras de Comercio Electr\u00f3nico<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Si tienes un sitio de e-commerce o una tienda en l\u00ednea, <\/span><a href=\"https:\/\/support.google.com\/analytics\/answer\/12200568?hl=es&amp;sjid=3799048339787975441-NA\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">configura el seguimiento de comercio electr\u00f3nico en GA4<\/span><\/a><span style=\"font-weight: 400;\">.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">As\u00ed podr\u00e1s ver todas las compras efectuadas en tu sitio web, ver cu\u00e1les de tus productos son m\u00e1s populares, o generan m\u00e1s ingresos, as\u00ed como otros datos para optimizar las ventas y hacer que tu negocio crezca.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-compras-en-la-aplicacion\"><strong>3. Compras en la Aplicaci\u00f3n<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Si tu sitio web o aplicaci\u00f3n ofrecen la opci\u00f3n de comprar (por ejemplo, m\u00e1s giros en la m\u00e1quina tragamonedas, o una suscripci\u00f3n de pago), puedes configurar esa acci\u00f3n como una compra.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Con este informe ver\u00e1s todas las compras, as\u00ed como datos de qui\u00e9n las hizo y desde d\u00f3nde. Para configurar esto, simplemente genera un evento con el nombre \u201cin_app_purchase\u201d al completar una compra.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-anuncios-de-editores\"><strong>4. Anuncios de Editores<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Digamos que monetizas tu sitio web o aplicaci\u00f3n con anuncios. Mira con este informe cu\u00e1nto ganas, cu\u00e1les anuncios generan m\u00e1s ingresos y cu\u00e1les p\u00e1ginas tienen m\u00e1s impresiones y clics. Este informe se integra directamente con Google Ad Manager o AdMob para generar datos. Si usas otra red de anuncios, necesitar\u00e1s migrar manualmente los datos de anuncios.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-5-promociones\"><strong>5. Promociones<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">El \u00faltimo informe de Monetizaci\u00f3n es el Informe de Promociones.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Este simplifica c\u00f3mo rastreas promociones como ofertas especiales, descuentos y cupones.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Tal vez ya creaste antes par\u00e1metros de seguimiento personalizados y otros sistemas en Universal Analytics, pero ahora podr\u00e1s configurar promociones espec\u00edficas y luego realizar un seguimiento de su impacto en tus ingresos.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Por ejemplo, puedes utilizar un banner ofreciendo un 10% de descuento en un producto y luego evaluar sus datos, para ver cu\u00e1ntas compras e ingresos gener\u00f3 esa promoci\u00f3n en espec\u00edfico.<\/span><\/p>\n\n\n\n<h2 id=\"h-informe-de-retencion\" class=\"wp-block-heading\"><strong><a id=\"retencion\"><\/a>Informe de Retenci\u00f3n<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">La separaci\u00f3n es, como dir\u00eda aquella canci\u00f3n de rock argentino, una \u201cdulce condena\u201d.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Pero si tus m\u00e9tricas de retenci\u00f3n est\u00e1n bien, no temas. Esos usuarios estar\u00e1n de vuelta en un abrir y cerrar de ojos.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">El informe de Retenci\u00f3n te dar\u00e1 un panorama simple de cu\u00e1ntos usuarios nuevos visitan tu sitio web, en comparaci\u00f3n con el n\u00famero de usuarios que lo visitaron antes y ahora regresaron.<\/span><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"900\" height=\"401\" data-src=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-general-retencion.jpg.webp\" alt=\"Conociendo el Informe de Resumen de Retenci\u00f3n.\" class=\"wp-image-40458 lazyload\" data-srcset=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-general-retencion.jpg.webp 900w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/Informe-general-retencion-300x134.jpg 300w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/Informe-general-retencion-768x342.jpg 768w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-general-retencion-600x267.jpg.webp 600w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-general-retencion-730x325.jpg.webp 730w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-general-retencion-784x349.jpg.webp 784w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-general-retencion-877x391.jpg.webp 877w\" data-sizes=\"(max-width: 900px) 100vw, 900px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 900px; --smush-placeholder-aspect-ratio: 900\/401;\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Da un paso m\u00e1s all\u00e1, al mirar la retenci\u00f3n a lo largo del tiempo, la retenci\u00f3n por cohorte y otros informes avanzados, para que entiendas mejor cu\u00e1ndo los usuarios son m\u00e1s propensos a regresar a tu sitio en el futuro.<\/span><\/p>\n\n\n\n<h2 id=\"h-informe-de-grupos-demograficos\" class=\"wp-block-heading\"><strong><a id=\"demografia\"><\/a>Informe de Grupos Demogr\u00e1ficos<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">\u00bfAlguna vez has querido acercarte, estrechar la mano de los visitantes de tu sitio y conocerlos?&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Bueno, eso ser\u00eda por dem\u00e1s inquietante. <\/span><span style=\"font-weight: 400;\"><br><\/span><span style=\"font-weight: 400;\"><br><\/span><span style=\"font-weight: 400;\">Pero lo que s\u00ed puedes hacer, es aprender sobre ellos a distancia, con el Informe de Grupos Demogr\u00e1ficos.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-resumen-1\"><strong>1. Resumen<\/strong><\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"900\" height=\"684\" data-src=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/informe-vista-general-Demografia.jpg.webp\" alt=\"Conociendo el Informe de Resumen de Grupos Demogr\u00e1ficos.\" class=\"wp-image-40451 lazyload\" data-srcset=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/informe-vista-general-Demografia.jpg.webp 900w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/informe-vista-general-Demografia-300x228.jpg 300w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/informe-vista-general-Demografia-768x584.jpg 768w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/informe-vista-general-Demografia-600x456.jpg.webp 600w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/informe-vista-general-Demografia-730x555.jpg.webp 730w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/informe-vista-general-Demografia-784x596.jpg.webp 784w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/informe-vista-general-Demografia-877x667.jpg.webp 877w\" data-sizes=\"(max-width: 900px) 100vw, 900px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 900px; --smush-placeholder-aspect-ratio: 900\/684;\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">El Informe de Resumen de Grupos Demogr\u00e1ficos tiene datos sobre qui\u00e9nes visitan tu sitio:<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">Ciudad y pa\u00eds<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Idioma<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Edad<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Intereses<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">G\u00e9nero<\/span><\/li>\n\n\n\n\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Podr\u00e1s ver si tu sitio web suele atraer visitantes desde ciertos pa\u00edses, o si es m\u00e1s popular entre hombres o mujeres. Estos datos ser\u00e1n \u00fatiles para actividades promocionales y de marketing.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-detalles-demograficos\"><strong>2. Detalles Demogr\u00e1ficos<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Aqu\u00ed se superponen los datos demogr\u00e1ficos del Resumen, con los del Informe de Participaci\u00f3n.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Entonces podr\u00e1s ver cu\u00e1les grupos visitan tu sitio con mayor frecuencia, as\u00ed como cu\u00e1les grupos est\u00e1n m\u00e1s involucrados, hacen m\u00e1s compras, pasan m\u00e1s tiempo en tu sitio web y m\u00e1s.<\/span><\/p>\n\n\n\n<h2 id=\"h-informe-de-tecnologia\" class=\"wp-block-heading\"><strong><a id=\"tecnologia\"><\/a>Informe de Tecnolog\u00eda<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Este informe te mostrar\u00e1 qu\u00e9 dispositivos, sistemas y navegadores usan las personas para visitar tu sitio web.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-resumen\"><strong>Resumen<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Este Resumen hace un desglose similar al del Informe de Grupos Demogr\u00e1ficos, destacando los tipos de sistemas y dispositivos que utilizan tus visitantes con frecuencia.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-detalles-de-la-tecnologia\"><span style=\"font-weight: 400;\">Detalles de la Tecnolog\u00eda<\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Estos detalles, similares tambi\u00e9n a los Demogr\u00e1ficos, correlacionan los diferentes dispositivos y tecnolog\u00edas de tus visitantes, junto con los datos de participaci\u00f3n. Puedes usar estos datos para hallar problemas, como un mal rendimiento del sitio en algunas pantallas o navegadores.<\/span><\/p>\n\n\n\n<h2 id=\"h-navegando-y-personalizando-tus-informes-de-ga4\" class=\"wp-block-heading\"><strong><a id=\"navegar\"><\/a>Navegando y Personalizando Tus Informes de GA4<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Una vez recorrido el mundo, veamos maneras de emplear la pesta\u00f1a Informes. As\u00ed, comprender\u00e1s mejor a tu audiencia, mientras tomas decisiones basadas en datos sobre tu sitio y negocio.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-aplicando-filtros\"><strong>Aplicando Filtros<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Con filtros, podr\u00e1s ver segmentos puntuales de tu tr\u00e1fico, y tambi\u00e9n comprender\u00e1s mejor c\u00f3mo algunos grupos de usuarios espec\u00edficos interact\u00faan con tu sitio.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Para aplicar alguno, solo abre cualquier informe de esta gu\u00eda. Busca <\/span><b>\u2018Agregar filtro\u2019<\/b><span style=\"font-weight: 400;\"> bajo el nombre del informe y haz clic en \u00e9l.<\/span><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"900\" height=\"303\" data-src=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-adquisicion-usuarios-personalizado-GA4.jpg.webp\" alt=\"Creando eventos en GA4.\" class=\"wp-image-40452 lazyload\" data-srcset=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-adquisicion-usuarios-personalizado-GA4.jpg.webp 900w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/Informe-adquisicion-usuarios-personalizado-GA4-300x101.jpg 300w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/Informe-adquisicion-usuarios-personalizado-GA4-768x259.jpg 768w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-adquisicion-usuarios-personalizado-GA4-600x202.jpg.webp 600w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-adquisicion-usuarios-personalizado-GA4-730x246.jpg.webp 730w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-adquisicion-usuarios-personalizado-GA4-784x264.jpg.webp 784w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/Informe-adquisicion-usuarios-personalizado-GA4-877x295.jpg.webp 877w\" data-sizes=\"(max-width: 900px) 100vw, 900px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 900px; --smush-placeholder-aspect-ratio: 900\/303;\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Ya aqu\u00ed, podr\u00e1s crear un filtro personalizado, basado en hasta 5 dimensiones diferentes.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-comparaciones\"><strong>Comparaciones<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Aqu\u00ed, podr\u00e1s ver c\u00f3mo dos grupos interact\u00faan cara a cara. Por ejemplo, podr\u00e1s comparar c\u00f3mo se comporta el tr\u00e1fico de b\u00fasqueda org\u00e1nica, junto al tr\u00e1fico de b\u00fasqueda paga.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Para generar una comparaci\u00f3n en cualquier informe de GA4, simplemente haz clic en <\/span><b>\u2018Agregar comparaci\u00f3n\u2019<\/b><span style=\"font-weight: 400;\">, encima del t\u00edtulo del informe.<\/span><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"900\" height=\"439\" data-src=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/informe-comparacion-interacciones-personalizado.jpg.webp\" alt=\"Agregando comparaciones, en cualquier informe de GA4.\" class=\"wp-image-40453 lazyload\" data-srcset=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/informe-comparacion-interacciones-personalizado.jpg.webp 900w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/informe-comparacion-interacciones-personalizado-300x146.jpg 300w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/informe-comparacion-interacciones-personalizado-768x375.jpg 768w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/informe-comparacion-interacciones-personalizado-600x293.jpg.webp 600w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/informe-comparacion-interacciones-personalizado-730x356.jpg.webp 730w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/informe-comparacion-interacciones-personalizado-784x382.jpg.webp 784w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/informe-comparacion-interacciones-personalizado-877x428.jpg.webp 877w\" data-sizes=\"(max-width: 900px) 100vw, 900px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 900px; --smush-placeholder-aspect-ratio: 900\/439;\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Despu\u00e9s, configura una comparaci\u00f3n, bas\u00e1ndote en la dimensi\u00f3n que desees segmentar.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-rangos-de-fechas\"><strong>Rangos de Fechas<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Cada informe de GA4 (excepto los de tiempo real) muestra datos de un rango de tiempo espec\u00edfico.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">De forma predeterminada, los informes mostrar\u00e1n <\/span><b>\u2018<\/b><span style=\"font-weight: 400;\">los \u00daltimos 28 D\u00edas<\/span><b>\u2019<\/b><span style=\"font-weight: 400;\">. Sin embargo, puedes cambiar ese rango de fechas cuando desees, simplemente haciendo clic en el rango de fechas que aparece en la esquina superior derecha del informe y estableciendo un nuevo rango.<\/span><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"900\" height=\"442\" data-src=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/reportes-personalizados-GA4.jpg.webp\" alt=\"Cambiando los rangos de fechas en cualquier informe de GA4.\" class=\"wp-image-40454 lazyload\" data-srcset=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/reportes-personalizados-GA4.jpg.webp 900w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/reportes-personalizados-GA4-300x147.jpg 300w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/reportes-personalizados-GA4-768x377.jpg 768w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/reportes-personalizados-GA4-600x295.jpg.webp 600w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/reportes-personalizados-GA4-730x359.jpg.webp 730w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/reportes-personalizados-GA4-784x385.jpg.webp 784w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2023\/05\/reportes-personalizados-GA4-877x431.jpg.webp 877w\" data-sizes=\"(max-width: 900px) 100vw, 900px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 900px; --smush-placeholder-aspect-ratio: 900\/442;\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"h-barra-de-busqueda\"><strong>Barra de B\u00fasqueda<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">\u00bfNo encuentras lo que buscas en GA4?&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">\u00a1Intenta usar la barra de b\u00fasqueda! <\/span><span style=\"font-weight: 400;\"><br><\/span><span style=\"font-weight: 400;\"><br><\/span><span style=\"font-weight: 400;\">En la parte superior de la ventana de GA4, la encontrar\u00e1s. All\u00ed puedes buscar informes o datos espec\u00edficos. O, hacer preguntas en lenguaje simple, utilizando la funci\u00f3n <\/span><a href=\"https:\/\/www.dreamhost.com\/blog\/es\/analytics-intelligence-en-ga4\/\" target=\"_blank\" rel=\"noopener\"><i><span style=\"font-weight: 400;\">Analytics Intelligence<\/span><\/i><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-informes-personalizados\"><strong>Informes Personalizados<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Los informes predeterminados existen para ofrecerte mucha informaci\u00f3n, pero no todas las mezclas son iguales. Esto depende de tu sitio web y negocio. <\/span><span style=\"font-weight: 400;\"><br><\/span><span style=\"font-weight: 400;\"><br><\/span><span style=\"font-weight: 400;\">La funci\u00f3n <\/span><b>\u2018<\/b><span style=\"font-weight: 400;\">Informes Personalizados<\/span><b>\u2019<\/b><span style=\"font-weight: 400;\"> es como tener tu propia helader\u00eda de anal\u00edticas.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Elige las dimensiones, m\u00e9tricas y filtros que prefieras, para luego mezclar y combinar todo y as\u00ed obtener un informe \u00fanico. Sea que prefieras una vista general m\u00e1s simple, o una extravagante explosi\u00f3n de datos, sabemos que los informes personalizados satisfar\u00e1n tu antojo de an\u00e1lisis.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Para crear un informe \u00fanico y personalizado, solo haz clic en <\/span><b>\u2018Biblioteca\u2019<\/b><span style=\"font-weight: 400;\">, en la parte inferior del men\u00fa de la pesta\u00f1a <\/span><b>\u2018Informes\u2019<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Incluso puedes personalizar las plantillas tradicionales de informes, para que te muestren los datos que deseas, tal y como quieras verlos.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">(Nota: Ten presente que necesitas acceso de Editor o Administrador para ver <\/span><b>\u2018Biblioteca\u2019<\/b><span style=\"font-weight: 400;\">).<\/span><\/p>\n\n\n\n<h2 id=\"h-mas-alla-de-la-pestana-informes\" class=\"wp-block-heading\"><strong><a id=\"alla\"><\/a>M\u00e1s All\u00e1 de la Pesta\u00f1a Informes<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Muy bien. Ya hemos cubierto un mont\u00f3n de informes que ver\u00e1s en GA4. Pero, en realidad, solo hemos revisado la superficie de todo lo que podr\u00e1s recopilar y analizar.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Aqu\u00ed hay algunas cosas adicionales que seguramente llamar\u00e1n tu atenci\u00f3n:<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-exploraciones-y-visualizaciones\"><strong>Exploraciones y Visualizaciones<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Una de las nuevas caracter\u00edsticas m\u00e1s populares de GA4 es la pesta\u00f1a \u2018Exploraciones\u2019.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Como en este art\u00edculo nos enfocamos en la pesta\u00f1a Informes, dejamos un poco de lado c\u00f3mo usar esta opci\u00f3n. Pero, para no olvidarla, debes saber que \u2018Exploraciones\u2019 desbloquea un conjunto realmente nuevo de capacidades.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Con Exploraciones GA4, podr\u00e1s hacer un an\u00e1lisis de datos libre y elegir tus visualizaciones personalizadas.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Por ejemplo, puedes crear un \u2018Embudo de Exploraci\u00f3n\u2019 y comprender c\u00f3mo los usuarios llegan a tu sitio web, y luego c\u00f3mo lo navegan. Tambi\u00e9n, puedes explorar rutas espec\u00edficas de usuario con la \u2018Ruta de Exploraci\u00f3n\u2019 y comparar visualmente segmentos de audiencia (\u00a1incluidas dimensiones secundarias!), con un an\u00e1lisis de \u2018Superposici\u00f3n de Segmentos\u2019.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-integraciones\"><strong>Integraciones<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Si realmente est\u00e1s listo para ensuciarte las manos, la capacidad de GA4 de producir informes personalizados, solo est\u00e1 limitada por tu imaginaci\u00f3n (y habilidades t\u00e9cnicas).<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">GA4 cuenta con una gran variedad de integraciones nativas y puede compartir datos con la mayor\u00eda de los productos comunes de Google y otras herramientas de an\u00e1lisis de datos.<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">GA4 se integra con Google Tag Manager para rastrear eventos personalizados y conversiones.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">GA4 se integra con BigQuery para hacer un an\u00e1lisis avanzado de datos, con comandos similares a SQL.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">GA4 se puede vincular con Google Search Console para hacer an\u00e1lisis y optimizaci\u00f3n SEO.<\/span><\/li>\n\n\n\n\n<\/ul>\n\n\n\n<h2 id=\"h-eso-es-todo-sobre-ga4-amigos\" class=\"wp-block-heading\"><strong><a id=\"resumen\"><\/a>\u00a1Eso Es Todo (Sobre GA4), Amigos!<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Esperamos que te haya sido muy \u00fatil esta gu\u00eda sobre los informes de GA4.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Aunque notar\u00e1s cambios importantes comparados con UA, acostumbrarse a esta nueva versi\u00f3n de Analytics solo tomar\u00e1 tiempo. Tras unos meses, ser\u00e1s todo un profesional que no pensar\u00e1 dos veces antes de extraer el informe perfecto de su flujo de datos.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">\u00a1Nos vemos cuando salga GA5!\u2026 O como sea que decidan nombrar a la pr\u00f3xima versi\u00f3n.<\/span><span style=\"font-weight: 400;\"><\/span><\/p>\n\n\n\n\n<div\n\tclass=\"article-cta-shared article-cta-small\"\n>\n    <div class=\"tr-img-wrap-outer jsLoading\"><img decoding=\"async\" class=\"js-img-lazy \" src=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/themes\/blog2018\/assets\/img\/lazy-loading-transparent.webp\" data-srcset=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/themes\/blog2018\/assets\/img\/article-small-ad-cta-placeholder.webp 1x, https:\/\/www.dreamhost.com\/blog\/wp-content\/themes\/blog2018\/assets\/img\/article-small-ad-cta-placeholder-x2.webp 2x\"  alt=\"Ad background image\" \/><\/div>\n\n\n\n\n  <div class=\"content-btm\">\n    <h2\n      class=\"h2--md\"\n    >\n      Recibe M\u00e1s Visitantes, Haz Crecer Tu Negocio\n    <\/h2>\n    <p\n      class=\"p--md\"\n    >\n      Nuestros expertos en marketing te ayudar\u00e1n a conseguir un mayor tr\u00e1fico y convertir m\u00e1s visitantes en compradores, mientras t\u00fa te concentras en dirigir tu empresa.\n    <\/p>\n\n            <a\n            href=\"https:\/\/www.dreamhost.com\/es\/servicios-profesionales\/marketing\/\"\n                        class=\"btn btn--white-outline btn--sm btn--round\"\n                                    target=\"_blank\"\n            rel=\"noopener noreferrer\"\n            >\n                            Comienza Hoy                    <\/a>\n\n  <\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Antes de GA4, hab\u00eda\u2026 \u2026 UA\u2026 Y, antes de UA, hab\u00eda\u2026 \u2026 GA\u2026 Y, antes de GA, hab\u00eda\u2026. \u2026 \u00bfUrchin? Bueno\u2026 Hablando en serio, no sabemos qui\u00e9n est\u00e1 a cargo de darle nombre a las cosas en Google. Pero aqu\u00ed estamos. Google Analytics 4 (GA4) es una gran herramienta para analizar el rendimiento de sitios [&hellip;]<\/p>\n","protected":false},"author":1074,"featured_media":40407,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_opengraph-title":"","_yoast_wpseo_opengraph-description":"Master acquisition, conversions, and insights with this guide","_yoast_wpseo_twitter-title":"","_yoast_wpseo_twitter-description":"","toc_headlines":"[[\"h-entendiendo-la-pestana-de-informes-de-ga4\",\"Entendiendo la Pesta\u00f1a de Informes de GA4\"],[\"h-informe-panoramico\",\"Informe Panor\u00e1mico\"],[\"h-informes-en-tiempo-real-en-ga4\",\"Informes en Tiempo Real en GA4\"],[\"h-informes-de-adquisicion\",\"Informes de Adquisici\u00f3n\"],[\"h-informes-de-interaccion\",\"Informes de Interacci\u00f3n\"],[\"h-informes-de-monetizacion\",\"Informes de Monetizaci\u00f3n\"],[\"h-informe-de-retencion\",\"Informe de Retenci\u00f3n\"],[\"h-informe-de-grupos-demograficos\",\"Informe de Grupos Demogr\u00e1ficos\"],[\"h-informe-de-tecnologia\",\"Informe de Tecnolog\u00eda\"],[\"h-navegando-y-personalizando-tus-informes-de-ga4\",\"Navegando y Personalizando Tus Informes de GA4\"],[\"h-mas-alla-de-la-pestana-informes\",\"M\u00e1s All\u00e1 de la Pesta\u00f1a Informes\"],[\"h-eso-es-todo-sobre-ga4-amigos\",\"\u00a1Eso Es Todo (Sobre GA4), Amigos!\"]]","hide_toc":false,"show_updated_at":"0","footnotes":""},"categories":[12844,11668],"tags":[],"class_list":["post-40443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-es","category-tutoriales"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.3 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Informes GA4: La Gu\u00eda Completa Sobre M\u00e9tricas - DreamHost<\/title>\n<meta name=\"description\" content=\"Conoce el potencial de GA4 con nuestra completa gu\u00eda de Informes. Aprende a analizar adquisiciones, conversiones y m\u00e1s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dreamhost.com\/blog\/es\/reportes-ga4-guia-adquisicion-conversiones\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reportes GA4: La Gu\u00eda Completa sobre Adquisici\u00f3n, Conversiones y M\u00e1s\" \/>\n<meta property=\"og:description\" content=\"Master acquisition, conversions, and insights with this guide\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dreamhost.com\/blog\/es\/reportes-ga4-guia-adquisicion-conversiones\/\" \/>\n<meta property=\"og:site_name\" content=\"DreamHost Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DreamHost\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-16T15:07:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-16T22:42:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/1220-x-628-GA4-Reports_-A-Comprehensive-Guide-to-Metrics-Conversions-and-More.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Calvin Schneider\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@dreamhost\" \/>\n<meta name=\"twitter:site\" content=\"@dreamhost\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Calvin Schneider\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutes\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Informes GA4: La Gu\u00eda Completa Sobre M\u00e9tricas - DreamHost","description":"Conoce el potencial de GA4 con nuestra completa gu\u00eda de Informes. Aprende a analizar adquisiciones, conversiones y m\u00e1s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dreamhost.com\/blog\/es\/reportes-ga4-guia-adquisicion-conversiones\/","og_locale":"en_US","og_type":"article","og_title":"Reportes GA4: La Gu\u00eda Completa sobre Adquisici\u00f3n, Conversiones y M\u00e1s","og_description":"Master acquisition, conversions, and insights with this guide","og_url":"https:\/\/www.dreamhost.com\/blog\/es\/reportes-ga4-guia-adquisicion-conversiones\/","og_site_name":"DreamHost Blog","article_publisher":"https:\/\/www.facebook.com\/DreamHost\/","article_published_time":"2023-05-16T15:07:39+00:00","article_modified_time":"2025-01-16T22:42:32+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/1220-x-628-GA4-Reports_-A-Comprehensive-Guide-to-Metrics-Conversions-and-More.jpg","type":"image\/jpeg"}],"author":"Calvin Schneider","twitter_card":"summary_large_image","twitter_creator":"@dreamhost","twitter_site":"@dreamhost","twitter_misc":{"Written by":"Calvin Schneider","Est. reading time":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.dreamhost.com\/blog\/es\/reportes-ga4-guia-adquisicion-conversiones\/#article","isPartOf":{"@id":"https:\/\/www.dreamhost.com\/blog\/es\/reportes-ga4-guia-adquisicion-conversiones\/"},"author":{"name":"Calvin Schneider","@id":"https:\/\/www.dreamhost.com\/blog\/#\/schema\/person\/25809c3eb45fb163988c10d4aefff33d"},"headline":"Reportes GA4: La Gu\u00eda Completa sobre Adquisici\u00f3n, Conversiones y M\u00e1s","datePublished":"2023-05-16T15:07:39+00:00","dateModified":"2025-01-16T22:42:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.dreamhost.com\/blog\/es\/reportes-ga4-guia-adquisicion-conversiones\/"},"wordCount":3158,"publisher":{"@id":"https:\/\/www.dreamhost.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.dreamhost.com\/blog\/es\/reportes-ga4-guia-adquisicion-conversiones\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/GA4-Reports-Hero-Image.jpg","articleSection":["Marketing","Tutoriales"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.dreamhost.com\/blog\/es\/reportes-ga4-guia-adquisicion-conversiones\/","url":"https:\/\/www.dreamhost.com\/blog\/es\/reportes-ga4-guia-adquisicion-conversiones\/","name":"Informes GA4: La Gu\u00eda Completa Sobre M\u00e9tricas - DreamHost","isPartOf":{"@id":"https:\/\/www.dreamhost.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dreamhost.com\/blog\/es\/reportes-ga4-guia-adquisicion-conversiones\/#primaryimage"},"image":{"@id":"https:\/\/www.dreamhost.com\/blog\/es\/reportes-ga4-guia-adquisicion-conversiones\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/GA4-Reports-Hero-Image.jpg","datePublished":"2023-05-16T15:07:39+00:00","dateModified":"2025-01-16T22:42:32+00:00","description":"Conoce el potencial de GA4 con nuestra completa gu\u00eda de Informes. Aprende a analizar adquisiciones, conversiones y m\u00e1s.","breadcrumb":{"@id":"https:\/\/www.dreamhost.com\/blog\/es\/reportes-ga4-guia-adquisicion-conversiones\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dreamhost.com\/blog\/es\/reportes-ga4-guia-adquisicion-conversiones\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dreamhost.com\/blog\/es\/reportes-ga4-guia-adquisicion-conversiones\/#primaryimage","url":"https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/GA4-Reports-Hero-Image.jpg","contentUrl":"https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/05\/GA4-Reports-Hero-Image.jpg","width":1460,"height":1095,"caption":"GA4 reports hero image"},{"@type":"BreadcrumbList","@id":"https:\/\/www.dreamhost.com\/blog\/es\/reportes-ga4-guia-adquisicion-conversiones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dreamhost.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Reportes GA4: La Gu\u00eda Completa sobre Adquisici\u00f3n, Conversiones y M\u00e1s"}]},{"@type":"WebSite","@id":"https:\/\/www.dreamhost.com\/blog\/#website","url":"https:\/\/www.dreamhost.com\/blog\/","name":"DreamHost Blog","description":"","publisher":{"@id":"https:\/\/www.dreamhost.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dreamhost.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.dreamhost.com\/blog\/#organization","name":"DreamHost","url":"https:\/\/www.dreamhost.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dreamhost.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhblog.dream.press\/blog\/wp-content\/uploads\/2019\/01\/dh_logo-blue-2.png","contentUrl":"https:\/\/dhblog.dream.press\/blog\/wp-content\/uploads\/2019\/01\/dh_logo-blue-2.png","width":1200,"height":168,"caption":"DreamHost"},"image":{"@id":"https:\/\/www.dreamhost.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DreamHost\/","https:\/\/x.com\/dreamhost","https:\/\/www.instagram.com\/dreamhost\/","https:\/\/www.linkedin.com\/company\/dreamhost\/","https:\/\/www.youtube.com\/user\/dreamhostusa"]},{"@type":"Person","@id":"https:\/\/www.dreamhost.com\/blog\/#\/schema\/person\/25809c3eb45fb163988c10d4aefff33d","name":"Calvin Schneider","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/03\/Calvin-Schneider-150x150.jpeg","url":"https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/03\/Calvin-Schneider-150x150.jpeg","contentUrl":"https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2023\/03\/Calvin-Schneider-150x150.jpeg","caption":"Calvin Schneider"},"description":"Calvin is VP of Data Science at DreamHost, responsible for delivering data-driven insights using customer and internal metrics. In his free time, Calvin enjoys traveling with his family, playing sports, and being a girl dad. Follow Calvin on LinkedIn https:\/\/www.linkedin.com\/in\/calvinschneiderphd\/","url":"https:\/\/www.dreamhost.com\/blog\/author\/calvinschneider\/"}]}},"lang":"es","translations":{"es":40443,"en":40406,"uk":50969,"pt":56563,"de":56566,"ru":56574,"pl":56600,"it":68883,"fr":71341,"nl":71374},"pll_sync_post":{},"_links":{"self":[{"href":"https:\/\/www.dreamhost.com\/blog\/wp-json\/wp\/v2\/posts\/40443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dreamhost.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dreamhost.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dreamhost.com\/blog\/wp-json\/wp\/v2\/users\/1074"}],"version-history":[{"count":10,"href":"https:\/\/www.dreamhost.com\/blog\/wp-json\/wp\/v2\/posts\/40443\/revisions"}],"predecessor-version":[{"id":63499,"href":"https:\/\/www.dreamhost.com\/blog\/wp-json\/wp\/v2\/posts\/40443\/revisions\/63499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dreamhost.com\/blog\/wp-json\/wp\/v2\/media\/40407"}],"wp:attachment":[{"href":"https:\/\/www.dreamhost.com\/blog\/wp-json\/wp\/v2\/media?parent=40443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dreamhost.com\/blog\/wp-json\/wp\/v2\/categories?post=40443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dreamhost.com\/blog\/wp-json\/wp\/v2\/tags?post=40443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}