{"id":26678,"date":"2020-09-04T07:00:45","date_gmt":"2020-09-04T14:00:45","guid":{"rendered":"https:\/\/dhblog.dream.press\/blog\/?p=26678"},"modified":"2025-01-16T13:15:41","modified_gmt":"2025-01-16T21:15:41","slug":"que-es-experiencia-de-usuario","status":"publish","type":"post","link":"https:\/\/www.dreamhost.com\/blog\/es\/que-es-experiencia-de-usuario\/","title":{"rendered":"\u00bfQu\u00e9 es la experiencia de usuario ?\u00bfY c\u00f3mo usarla para crear un sitio ajustado a tu audiencia?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">\u00a1Qu\u00e9 momento para estar vivo!<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.dreamhost.com\/blog\/es\/disenar-sitio-web-sin-codigo\/\"><span style=\"font-weight: 400;\">Los principiantes sin experiencia en c\u00f3digo ahora pueden construir un sitio<\/span><\/a><span style=\"font-weight: 400;\"> con un esfuerzo y gastos m\u00ednimos. A\u00fan mejor, las opciones son infinitas: tienes un arsenal entero de colores, fuentes, im\u00e1genes, y botones a tu disposici\u00f3n. Pero con tantos elementos de dise\u00f1o para jugar, puede ser tentador volverse un poco loco.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">\u201c\u00a1Una chispa de animaci\u00f3n por aqu\u00ed! \u00a1Una pizca de animal print por all\u00e1!\u201d<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Pero, como es usualmente el caso con las cosas que brillan, es f\u00e1cil pasarse de la cuenta \u2014 especialmente si tu creatividad est\u00e1 reduciendo la funcionalidad de tu sitio.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Ya sea que quieres vender un producto o <\/span><a href=\"https:\/\/www.dreamhost.com\/blog\/es\/como-empezar-un-blog-guia\/\"><span style=\"font-weight: 400;\">compartir algunas publicaciones de blog<\/span><\/a><span style=\"font-weight: 400;\">, realmente no est\u00e1s construyendo el sitio para ti. Son los visitantes de tu sitio los que necesitan estar felices con tu dise\u00f1o e interfaz de usuario. Ah\u00ed es donde la Experiencia de Usuario (UX) entra en juego. Mantener un enfoque fuerte en el UX mientras que construyes tu sitio deber\u00eda valer la pena en mayores conversiones y tasas de rebote m\u00e1s bajas.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">En este art\u00edculo, te dar\u00e9 un curso intensivo sobre UX y te explicar\u00e9 lo que hace un dise\u00f1ador UX. Luego, veremos algunos consejos sobre reconocer un buen dise\u00f1o UX cuenco lo encuentras. Finalmente, te mostrar\u00e9 como usar UX para crear un mejor sitio web para tu audiencia. \u00a1Si\u00e9ntete libre de saltar a la secci\u00f3n que m\u00e1s te beneficie!<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"#Experiencia-usuario\"><span style=\"font-weight: 400;\">\u00bfQu\u00e9 es experiencia de usuario?<\/span><\/a><\/li>\n\n\n\n<li><a href=\"#Profesional-UX\"><span style=\"font-weight: 400;\">\u00bfQu\u00e9 hace un profesional de UX?<\/span><\/a><\/li>\n\n\n\n<li><a href=\"#Diseno-UX\"><span style=\"font-weight: 400;\">\u00bfQu\u00e9 constituye un buen dise\u00f1o UX?<\/span><\/a><\/li>\n\n\n\n<li><a href=\"#Experiencia-positiva\"><span style=\"font-weight: 400;\">\u00bfC\u00f3mo puedes crear una experiencia de usuario positiva en tu sitio?<\/span><\/a><\/li>\n\n\n\n<li><a href=\"#recursos-UX\"><span style=\"font-weight: 400;\">Lista de los mejores recursos UX<\/span><\/a><\/li>\n\n\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">\u00bfListo para hablar de la estrategia UX? \u00a1Comencemos!<\/span><\/p>\n\n\n\n<h2 id=\"h-una-introduccion-a-la-experiencia-de-usuario-ux-y-por-que-es-importante\" class=\"wp-block-heading\"><b><a id=\"Experiencia-usuario\"><\/a>Una introducci\u00f3n a la Experiencia de Usuario (UX) y por qu\u00e9 es importante<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">En palabras simples, la Experiencia de Usuario (UX) es como se siente tu usuario al interactuar con la tecnolog\u00eda. El UX aplica a cualquier tecnolog\u00eda, desde una aplicaci\u00f3n a una consola de juegos.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Cuando se trata de sitios web, el dise\u00f1o UX se trata de optimizar la interacci\u00f3n entre el usuario humano y la p\u00e1gina. Un sitio creado con principios de UX s\u00f3lidos deben dejar al usuario sentir que ha cumplido su objetivo sin frustraci\u00f3n alguna.&nbsp;&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Esto te puede hacer pensar en hacer todo lo posible con el dise\u00f1o visual del sitio web. Esto puede incluir animaciones llamativas y carruseles de im\u00e1genes gigantes. Si recuerdas MySpace, probablemente a\u00fan tienes pesadillas sobre la brillantina animada y versiones MIDI de canciones de Blink-182\u2026 \u00a1uff!.&nbsp;<\/span><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"900\" height=\"345\" data-src=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/6b708057-701f-400a-a361-338e99be9977_dh-what-is-ux-5-1.jpg.webp\" alt=\"Un perfil de MySpace usando muchos colores y brillantina.\u00a0\" class=\"wp-image-26693 lazyload\" data-srcset=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/6b708057-701f-400a-a361-338e99be9977_dh-what-is-ux-5-1.jpg.webp 900w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2020\/09\/6b708057-701f-400a-a361-338e99be9977_dh-what-is-ux-5-1-300x115.jpg 300w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2020\/09\/6b708057-701f-400a-a361-338e99be9977_dh-what-is-ux-5-1-768x294.jpg 768w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/6b708057-701f-400a-a361-338e99be9977_dh-what-is-ux-5-1-600x230.jpg.webp 600w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/6b708057-701f-400a-a361-338e99be9977_dh-what-is-ux-5-1-730x280.jpg.webp 730w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/6b708057-701f-400a-a361-338e99be9977_dh-what-is-ux-5-1-784x301.jpg.webp 784w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/6b708057-701f-400a-a361-338e99be9977_dh-what-is-ux-5-1-877x336.jpg.webp 877w\" data-sizes=\"(max-width: 900px) 100vw, 900px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 900px; --smush-placeholder-aspect-ratio: 900\/345;\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Pero el dise\u00f1o UX tiene mucho menos que ver con c\u00f3mo se ve el sitio y m\u00e1s con c\u00f3mo es usado. Para ser efectivo, tu sitio web deber\u00eda ser una experiencia completa \u2014 no solo palabras e im\u00e1genes en una p\u00e1gina.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Los usuarios olvidar\u00e1n informaci\u00f3n, as\u00ed como cu\u00e1nto han pagado por los productos que han ordenado. Sin embargo, la experiencia de ordenar deber\u00eda ser placentera y sin esfuerzo. Esa experiencia se va a quedar con ellos, incrementando las posibilidades de que compren en tu tienda de nuevo.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Si tu sitio entrega un pobre UX, podr\u00e1s ver un resultado opuesto. Los usuarios que se estresan o se enojan cuando est\u00e1n usando tu sitio, probablemente se dirijan al sitio web de tus competidores. Ellos tienen muchas opciones y ninguna raz\u00f3n para regresar a un sitio web que es dif\u00edcil de usar.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Si a\u00fan no est\u00e1s convencido de que el UX importa en tu sitio web, aqu\u00ed hay algunas estad\u00edsticas clave:<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.pwc.com\/future-of-cx\"><span style=\"font-weight: 400;\">17 por ciento de los usuarios no regresar\u00e1n<\/span><\/a><span style=\"font-weight: 400;\"> despu\u00e9s de una sola mala experiencia.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Un mejor dise\u00f1o UX puede <\/span><a href=\"https:\/\/www.forbes.com\/sites\/forbesagencycouncil\/2017\/03\/23\/the-bottom-line-why-good-ux-design-means-better-business\/#2cd7223b2396\"><span style=\"font-weight: 400;\">incrementar tus tasas de conversi\u00f3n<\/span><\/a><span style=\"font-weight: 400;\"> hasta un 200 por ciento.<\/span><\/li>\n\n\n\n<li><a href=\"https:\/\/www.thinkwithgoogle.com\/advertising-channels\/mobile-marketing\/what-users-want-most-from-mobile-sites-today\/\"><span style=\"font-weight: 400;\">48 por ciento de los usuarios se molestan<\/span><\/a><span style=\"font-weight: 400;\"> por que los sitios no son amigables con dispositivos m\u00f3viles.<\/span><\/li>\n\n\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Todo esto sirve para ilustrar la importancia de un buen dise\u00f1o UX cuando est\u00e1s construyendo un sitio web.&nbsp;<\/span><\/p>\n\n\n<div class=\"single__related-article\">\n\t<span>Related Article<\/span>\n\t<div class=\"single__related-article__wrap\">\n\t\t<div class=\"single__related-article__title\">\n\t\t\tC\u00f3mo Construir P\u00e1ginas de Destino en WordPress Que Generen Leads\n\t\t<\/div>\n\t\t<a href=\"https:\/\/www.dreamhost.com\/blog\/es\/crear-pagina-destino-leads\/\" class=\"btn btn--sm btn--brand\" target=\"_blank\" rel=\"noopener\">\n\t\t\tRead More\n\t\t<\/a>\n\t<\/div>\n<\/div>\n\n\n<h2 id=\"h-el-papel-del-disenador-ux\" class=\"wp-block-heading\"><b><a id=\"Profesional-UX\"><\/a>El papel del dise\u00f1ador UX<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">El UX es tan importante que hay una profesi\u00f3n entera dedicada a optimizarlo. Las tareas diarias de un dise\u00f1ador var\u00edan dependiendo en qu\u00e9 tipo de proyectos est\u00e9n trabajando. Sin embargo, el objetivo es usualmente el mismo. <\/span><b>El trabajo de un dise\u00f1ador UX es optimizar la experiencia del usuario <\/b><span style=\"font-weight: 400;\">cuando est\u00e1 interactuando con tecnolog\u00eda digital teniendo en cuenta el bienestar del negocio.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Para lograr este acto de balanceo, el dise\u00f1ador UX sigue un proceso que <\/span><a href=\"https:\/\/www.interaction-design.org\/literature\/article\/7-ux-deliverables-what-will-i-be-making-as-a-ux-designer\"><span style=\"font-weight: 400;\">resulta en entregas m\u00faltiples<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Antes de que cualquier dise\u00f1o empiece, hay mucho por investigar sobre UX. De manera que, el dise\u00f1ador puede crear primero una o m\u00e1s <\/span><a href=\"https:\/\/www.usability.gov\/how-to-and-tools\/methods\/personas.html\"><span style=\"font-weight: 400;\">personas como audiencias<\/span><\/a><span style=\"font-weight: 400;\">. Esto permite que el dise\u00f1ador comprenda las necesidades de los usuarios.&nbsp;&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Seguido, el dise\u00f1ador UX puede presentar un diagrama de flujo de usuario, para ayudar a explorar posibles maneras en las que el usuario puede interactuar con el sitio web. Pueden entonces traducir la informaci\u00f3n en un prototipo. Los prototipos pueden ser tan simples como <\/span><a href=\"https:\/\/www.dreamhost.com\/blog\/es\/crear-usar-wireframes-sitios-web-guia\/\"><span style=\"font-weight: 400;\">un <\/span><i><span style=\"font-weight: 400;\">wireframe<\/span><\/i><\/a><i><span style=\"font-weight: 400;\">, <\/span><\/i><span style=\"font-weight: 400;\">un <\/span><i><span style=\"font-weight: 400;\">blueprint <\/span><\/i><span style=\"font-weight: 400;\">de como se ver\u00e1 la p\u00e1gina web al final. El dise\u00f1ador tambi\u00e9n puede crear un prototipo visualmente m\u00e1s robusto o uno con el que se pueda interactuar.&nbsp;<\/span><\/p>\n\n\n<div class=\"wp-block-image wp-image-26695 size-full\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"900\" height=\"625\" data-src=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/b8af0872-4f45-4c9e-875b-b33249d5346f_dh-what-is-ux-1-1.jpg.webp\" alt=\"Un bosquejo b\u00e1sico para dise\u00f1ar un sitio web.\" class=\"wp-image-26695 lazyload\" data-srcset=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/b8af0872-4f45-4c9e-875b-b33249d5346f_dh-what-is-ux-1-1.jpg.webp 900w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2020\/09\/b8af0872-4f45-4c9e-875b-b33249d5346f_dh-what-is-ux-1-1-300x208.jpg 300w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2020\/09\/b8af0872-4f45-4c9e-875b-b33249d5346f_dh-what-is-ux-1-1-768x533.jpg 768w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/b8af0872-4f45-4c9e-875b-b33249d5346f_dh-what-is-ux-1-1-600x417.jpg.webp 600w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/b8af0872-4f45-4c9e-875b-b33249d5346f_dh-what-is-ux-1-1-730x507.jpg.webp 730w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/b8af0872-4f45-4c9e-875b-b33249d5346f_dh-what-is-ux-1-1-784x544.jpg.webp 784w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/b8af0872-4f45-4c9e-875b-b33249d5346f_dh-what-is-ux-1-1-877x609.jpg.webp 877w\" data-sizes=\"(max-width: 900px) 100vw, 900px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 900px; --smush-placeholder-aspect-ratio: 900\/625;\" \/><figcaption class=\"wp-element-caption\">Un bosquejo b\u00e1sico.<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Las responsabilidades de un dise\u00f1ador UX no terminan con el dise\u00f1o final. Una vez que el sitio es publicado, pueden conducir una prueba de usabilidad o ver el uso de analytics para identificar y corregir problemas potenciales.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">En otras palabras, est\u00e1n involucrados en todas las etapas de la creaci\u00f3n y publicaci\u00f3n de un sitio web.<\/span><\/p>\n\n\n<div class=\"single__related-article\">\n\t<span>Related Article<\/span>\n\t<div class=\"single__related-article__wrap\">\n\t\t<div class=\"single__related-article__title\">\n\t\t\tObt\u00e9n M\u00e1s Conversiones Con Estos Tips Sobre Pruebas A\/B Para P\u00e1ginas de Destino\n\t\t<\/div>\n\t\t<a href=\"https:\/\/www.dreamhost.com\/blog\/es\/paginas-de-destino-pruebas-ab\/\" class=\"btn btn--sm btn--brand\" target=\"_blank\" rel=\"noopener\">\n\t\t\tRead More\n\t\t<\/a>\n\t<\/div>\n<\/div>\n\n\n<h2 id=\"h-como-reconocer-un-buen-diseno-ux\" class=\"wp-block-heading\"><b><a id=\"Diseno-UX\"><\/a>C\u00f3mo reconocer un buen dise\u00f1o UX<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Si est\u00e1s manejando tu propio dise\u00f1o UX, es tu responsabilidad abogar por tu audiencia mientras que te aseguras de que a\u00fan est\u00e1s obteniendo lo que quieres de tu sitio web. Para eso, el primer paso es aprender c\u00f3mo reconocer un dise\u00f1o robusto de UX.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Con eso en mente, veamos algunos ejemplos de UX en su h\u00e1bitat natural. Hay cuatro elementos clave a los que querr\u00e1s poner mucha atenci\u00f3n.&nbsp;<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-navegacion\"><b>1. Navegaci\u00f3n<\/b><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">El dise\u00f1o pobre de navegaci\u00f3n puede volver in\u00fatil a un sitio web. Moverse a trav\u00e9s del sitio debe ser intuitivo y f\u00e1cil. El men\u00fa de navegaci\u00f3n, tambi\u00e9n debe ser accesible sin importar qu\u00e9 dispositivo est\u00e1 usando el visitante.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">La <\/span><a href=\"https:\/\/www.justinmind.com\/blog\/4-tips-on-prototyping-breadcrumb-navigation-with-justinmind\/\"><span style=\"font-weight: 400;\">navegaci\u00f3n Breadcrumb<\/span><\/a><span style=\"font-weight: 400;\"> o miga de pan en espa\u00f1ol, es una forma que los dise\u00f1adores usan para prevenir que los usuarios se pierdan,&nbsp; especialmente si el sitio web tiene muchas p\u00e1ginas.<\/span><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"900\" height=\"439\" data-src=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/e9db2b0f-8fd6-4c8e-9a30-2ec3dd58b0a2_dh-what-is-ux-4-1.jpg.webp\" alt=\"Sitio web de H-E-B, usando una barra de navegaci\u00f3n y breadcrumbs.\" class=\"wp-image-26697 lazyload\" data-srcset=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/e9db2b0f-8fd6-4c8e-9a30-2ec3dd58b0a2_dh-what-is-ux-4-1.jpg.webp 900w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2020\/09\/e9db2b0f-8fd6-4c8e-9a30-2ec3dd58b0a2_dh-what-is-ux-4-1-300x146.jpg 300w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2020\/09\/e9db2b0f-8fd6-4c8e-9a30-2ec3dd58b0a2_dh-what-is-ux-4-1-768x375.jpg 768w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/e9db2b0f-8fd6-4c8e-9a30-2ec3dd58b0a2_dh-what-is-ux-4-1-600x293.jpg.webp 600w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/e9db2b0f-8fd6-4c8e-9a30-2ec3dd58b0a2_dh-what-is-ux-4-1-730x356.jpg.webp 730w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/e9db2b0f-8fd6-4c8e-9a30-2ec3dd58b0a2_dh-what-is-ux-4-1-784x382.jpg.webp 784w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/e9db2b0f-8fd6-4c8e-9a30-2ec3dd58b0a2_dh-what-is-ux-4-1-877x428.jpg.webp 877w\" data-sizes=\"(max-width: 900px) 100vw, 900px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 900px; --smush-placeholder-aspect-ratio: 900\/439;\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Tambi\u00e9n es importante ponerle atenci\u00f3n a los enlaces. Los dise\u00f1adores web que emplean un UX fuerte, se aseguran que puedes identificar los enlaces cuando los ves. Esto usualmente quiere decir subrayarlos y usar un color diferente. Tambi\u00e9n usualmente usan <\/span><a href=\"https:\/\/moz.com\/learn\/seo\/anchor-text\"><span style=\"font-weight: 400;\">texto de anclaje significativo<\/span><\/a><span style=\"font-weight: 400;\">, para que sepas a d\u00f3nde te est\u00e1 llevando el enlace antes de hacer clic en \u00e9l.&nbsp;<\/span><\/p>\n\n\n<div class=\"single__related-article\">\n\t<span>Related Article<\/span>\n\t<div class=\"single__related-article__wrap\">\n\t\t<div class=\"single__related-article__title\">\n\t\t\tC\u00f3mo Escribir una Publicaci\u00f3n de Blog (10 Secretos Para el \u00c9xito)\n\t\t<\/div>\n\t\t<a href=\"https:\/\/www.dreamhost.com\/blog\/es\/como-escribir-una-publicacion-de-blog\/\" class=\"btn btn--sm btn--brand\" target=\"_blank\" rel=\"noopener\">\n\t\t\tRead More\n\t\t<\/a>\n\t<\/div>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-contenido\"><b>2. Contenido<\/b><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Una parte significante del \u00e9xito del UX es entender c\u00f3mo interact\u00faa la gente con diferentes partes de un sitio web. Por ejemplo, la mayor\u00eda de las personas no leen contenido de las p\u00e1ginas web normalmente. <\/span><a href=\"https:\/\/www.nngroup.com\/articles\/how-users-read-on-the-web\/\"><span style=\"font-weight: 400;\">Lo escanean<\/span><\/a><span style=\"font-weight: 400;\"> y luego paran para leer si encontraron algo interesante.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">El contenido es escaneable si un usuario puede navegar r\u00e1pidamente a trav\u00e9s de una publicaci\u00f3n de blog o una p\u00e1gina de ventas y obtener una idea de lo que est\u00e1 comunicando.&nbsp;<\/span><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"765\" height=\"582\" data-src=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/ff4a85e0-503f-4fa1-a6df-f6562ea1c60e_dh-what-is-ux-3-1.jpg.webp\" alt=\"Contenido escaneable usando encabezados, p\u00e1rrafos cortos, y una lista con vi\u00f1etas.\" class=\"wp-image-26701 lazyload\" data-srcset=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/ff4a85e0-503f-4fa1-a6df-f6562ea1c60e_dh-what-is-ux-3-1.jpg.webp 765w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2020\/09\/ff4a85e0-503f-4fa1-a6df-f6562ea1c60e_dh-what-is-ux-3-1-300x228.jpg 300w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/ff4a85e0-503f-4fa1-a6df-f6562ea1c60e_dh-what-is-ux-3-1-600x456.jpg.webp 600w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/ff4a85e0-503f-4fa1-a6df-f6562ea1c60e_dh-what-is-ux-3-1-730x555.jpg.webp 730w\" data-sizes=\"(max-width: 765px) 100vw, 765px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 765px; --smush-placeholder-aspect-ratio: 765\/582;\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Mantener los p\u00e1rrafos cortos es una manera de crear un contenido f\u00e1cil de escanear. Esos p\u00e1rrafos deben estar divididos frecuentemente con encabezados, listas, e im\u00e1genes. Los dise\u00f1adores tambi\u00e9n pueden usar frases claves, texto en negrita y elementos similares.<\/span><\/p>\n\n\n<div class=\"single__related-article\">\n\t<span>Related Article<\/span>\n\t<div class=\"single__related-article__wrap\">\n\t\t<div class=\"single__related-article__title\">\n\t\t\tC\u00f3mo Empezar un Blog (Estrategia, Consejos e Ideas de Contenido)\n\t\t<\/div>\n\t\t<a href=\"https:\/\/www.dreamhost.com\/blog\/es\/como-empezar-un-blog-guia\/\" class=\"btn btn--sm btn--brand\" target=\"_blank\" rel=\"noopener\">\n\t\t\tRead More\n\t\t<\/a>\n\t<\/div>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-animacion\"><b>3. Animaci\u00f3n<\/b><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">La animaci\u00f3n es una forma efectiva de resaltar en un mar de sitios web y <\/span><a href=\"https:\/\/powerdigitalmarketing.com\/blog\/importance-of-web-animations\"><span style=\"font-weight: 400;\">atrapar la atenci\u00f3n del usuario<\/span><\/a><span style=\"font-weight: 400;\">. A\u00f1ade un elemento divertido y puede contribuir a crear una experiencia memorable para el usuario.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Sin embargo, hay una forma&nbsp; de acertar y otra de fallar cuando lo implementas.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.nngroup.com\/articles\/animation-purpose-ux\/#:~:text=In%20UX%2C%20motion%20and%20animation,induce%20delight%20or%20entertain%20users.&amp;text=The%20big%20advantage%20(and%20also,that%20it%20attracts%20user%20attention.\"><span style=\"font-weight: 400;\">La animaci\u00f3n sutil puede proveer retroalimentaci\u00f3n<\/span><\/a><span style=\"font-weight: 400;\"> mientras que esperas a que una transacci\u00f3n se complete. Una animaci\u00f3n tambi\u00e9n puede repetirse infinitamente mientras que luchas para concentrarte en leer la descripci\u00f3n de un producto. Estos enfoques crean dos experiencias bastante diferentes. El sobreuso de la animaci\u00f3n, tambi\u00e9n puede afectar el UX en dispositivos m\u00f3viles.&nbsp;&nbsp;<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-sensibilidad\"><b>4. Sensibilidad<\/b><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.dreamhost.com\/blog\/es\/como-optimizar-tu-sitio-dispositivos-moviles\/\"><span style=\"font-weight: 400;\">Optimizar un sitio web para usuarios m\u00f3viles<\/span><\/a><span style=\"font-weight: 400;\"> es necesario. Si eres como la mayor\u00eda de personas, <\/span><a href=\"https:\/\/www.census.gov\/library\/stories\/2018\/08\/internet-access.html#:~:text=How%20Households%20Access%20the%20Internet&amp;text=Overall%2C%20most%20households%20combine%20mobile,or%20other%20types%20of%20service.\"><span style=\"font-weight: 400;\">usualmente usas tu tel\u00e9fono<\/span><\/a><span style=\"font-weight: 400;\"> para acceder al internet. Si te encuentras un sitio con el que tienes que luchar para poder verlo en tu dispositivo, probablemente la abandonaras.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">M\u00e1s all\u00e1 de <\/span><a href=\"https:\/\/www.dreamhost.com\/blog\/es\/18-tips-profesionales-para-elegir-el-tema-perfecto-de-wordpress\/\"><span style=\"font-weight: 400;\">escoger un tema sensible<\/span><\/a><span style=\"font-weight: 400;\">, puedes tomar pasos adicionales para asegurarte de que tu sitio funciona bien en todas las pantallas. Por ejemplo, puedes administrar tu sitio web a trav\u00e9s de la <\/span><a href=\"https:\/\/search.google.com\/test\/mobile-friendly\"><span style=\"font-weight: 400;\">herramienta de Google de prueba de dispositivos m\u00f3viles<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"900\" height=\"294\" data-src=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/3a63f433-6f6b-4615-8e3c-2a4ee5b2cc0f_dh-what-is-ux-2-1.jpg.webp\" alt=\"Ejemplo de un resultado de la herramienta de prueba de dispositivos m\u00f3viles de Google.\" class=\"wp-image-26703 lazyload\" data-srcset=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/3a63f433-6f6b-4615-8e3c-2a4ee5b2cc0f_dh-what-is-ux-2-1.jpg.webp 900w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2020\/09\/3a63f433-6f6b-4615-8e3c-2a4ee5b2cc0f_dh-what-is-ux-2-1-300x98.jpg 300w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2020\/09\/3a63f433-6f6b-4615-8e3c-2a4ee5b2cc0f_dh-what-is-ux-2-1-768x251.jpg 768w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/3a63f433-6f6b-4615-8e3c-2a4ee5b2cc0f_dh-what-is-ux-2-1-600x196.jpg.webp 600w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/3a63f433-6f6b-4615-8e3c-2a4ee5b2cc0f_dh-what-is-ux-2-1-730x238.jpg.webp 730w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/3a63f433-6f6b-4615-8e3c-2a4ee5b2cc0f_dh-what-is-ux-2-1-784x256.jpg.webp 784w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/3a63f433-6f6b-4615-8e3c-2a4ee5b2cc0f_dh-what-is-ux-2-1-877x286.jpg.webp 877w\" data-sizes=\"(max-width: 900px) 100vw, 900px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 900px; --smush-placeholder-aspect-ratio: 900\/294;\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Esta herramienta te alertar\u00e1 sobre los posibles problemas que est\u00e1n previniendo que tu sitio sea amigable con los dispositivos m\u00f3viles. Puedes encontrar que una fuente en part\u00edculas es muy dif\u00edcil de leer en una pantalla peque\u00f1a, por ejemplo, o que los botones son muy peque\u00f1os para presionar f\u00e1cilmente.&nbsp;<\/span><\/p>\n\n\n<div class=\"single__related-article\">\n\t<span>Related Article<\/span>\n\t<div class=\"single__related-article__wrap\">\n\t\t<div class=\"single__related-article__title\">\n\t\t\tDe Clics a Clientes: 23 T\u00e9cnicas y Herramientas para Mejorar las Tasas de Conversi\u00f3n de Tu Sitio Web\n\t\t<\/div>\n\t\t<a href=\"https:\/\/www.dreamhost.com\/blog\/es\/incrementar-tasa-conversion-sitio-web\/\" class=\"btn btn--sm btn--brand\" target=\"_blank\" rel=\"noopener\">\n\t\t\tRead More\n\t\t<\/a>\n\t<\/div>\n<\/div>\n\n\n<h2 id=\"h-como-usar-ux-para-disenar-un-sitio-para-tu-audiencia\" class=\"wp-block-heading\"><b><a id=\"Experiencia-positiva\"><\/a>C\u00f3mo usar UX para dise\u00f1ar un sitio para tu audiencia<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Ahora que sabes que es un buen UX, \u00bfc\u00f3mo lo aplicas a tu sitio?<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Probablemente no vas a estar haciendo una investigaci\u00f3n de mercadeo intensiva y tampoco usar\u00e1s un prototipo de prueba de alta fidelidad. Aun as\u00ed, ponerte el sombrero de dise\u00f1ador UX puede ayudarte a crear un sitio que ambos t\u00fa y t\u00fa audiencia amar\u00e1n.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Primero, es importante ser claro sobre por qu\u00e9 tienes un sitio web y que quieres que haga. Por ejemplo, est\u00e1s:&nbsp;<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.dreamhost.com\/blog\/ways-to-get-first-sale-new-ecommerce-site\/\"><span style=\"font-weight: 400;\">\u00bfVendiendo un producto en un sitio e-commerce?<\/span><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.dreamhost.com\/blog\/how-to-monetize-your-blog\/\"><span style=\"font-weight: 400;\">\u00bfCreando contenido para generar ganancias<\/span><\/a><span style=\"font-weight: 400;\"> (por ejemplo, <\/span><a href=\"https:\/\/www.dreamhost.com\/blog\/how-to-start-a-food-blog\/\"><span style=\"font-weight: 400;\">blogueando sobre comida<\/span><\/a><span style=\"font-weight: 400;\"> o <\/span><a href=\"https:\/\/www.dreamhost.com\/blog\/how-to-start-fitness-blog\/\"><span style=\"font-weight: 400;\">fitness<\/span><\/a><span style=\"font-weight: 400;\">)?<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">\u00bf<\/span><a href=\"https:\/\/www.dreamhost.com\/blog\/es\/guia-para-principiantes-marketing-afiliados\/\"><span style=\"font-weight: 400;\">Administrando una p\u00e1gina de afiliados<\/span><\/a><span style=\"font-weight: 400;\">?<\/span><\/li>\n\n\n\n<li><a href=\"https:\/\/www.dreamhost.com\/blog\/es\/como-crear-un-sitio-escritor-freelance\/\"><span style=\"font-weight: 400;\">\u00bfTratando de ser contratado para trabajos como independiente<\/span><\/a><span style=\"font-weight: 400;\">?<\/span><\/li>\n\n\n\n<li><a href=\"https:\/\/www.dreamhost.com\/blog\/build-your-online-portfolio-fast\/\"><span style=\"font-weight: 400;\">\u00bfPromoviendo tus servicios con un portafolio en l\u00ednea<\/span><\/a><span style=\"font-weight: 400;\">?<\/span><\/li>\n\n\n\n<li><a href=\"https:\/\/www.dreamhost.com\/blog\/website-benefits-for-small-business\/\"><span style=\"font-weight: 400;\">\u00bfConstruyendo una presencia en l\u00ednea para tu negocio f\u00edsico<\/span><\/a><span style=\"font-weight: 400;\">?<\/span><\/li>\n\n\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Seguido, conoce tu usuario ideal o cliente potencial. <\/span><a href=\"https:\/\/uxmastery.com\/create-ux-personas\/\"><span style=\"font-weight: 400;\">Crear un usuario persona<\/span><\/a><span style=\"font-weight: 400;\"> te ayudar\u00e1 a imaginar c\u00f3mo tu audiencia objetiva puede interactuar con tu sitio web. Esta persona puede ser tan simple como qui\u00e9n es el usuario, que quiere, y qu\u00e9 lo mantiene interesado. Crucialmente, debes identificar lo que el usuario necesita para ser exitoso en tu sitio web.&nbsp;&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Recuerda que la <\/span><b>accesibilidad es una parte integral del UX.<\/b><span style=\"font-weight: 400;\"> Puedes tener visitantes que usan tecnolog\u00eda asistiva, as\u00ed que considera <\/span><a href=\"https:\/\/www.dreamhost.com\/blog\/es\/volver-tu-pagina-web-accesible\/\"><span style=\"font-weight: 400;\">hacer de la accesibilidad una prioridad<\/span><\/a><span style=\"font-weight: 400;\"> cuando construyas tu sitio.&nbsp;&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Tambi\u00e9n puedes echarle un ojo a los sitios de tus competidores para ver que est\u00e1 funcionando para ellos. \u00bfEl icono del carrito de compras siempre est\u00e1 en la esquina superior derecha? Tal vez el tuyo tambi\u00e9n deber\u00eda estarlo. Puedes ser creativo sin reinventar la rueda; los usuarios no deber\u00edan tener que descifrar c\u00f3mo funciona tu sitio para cumplir sus objetivos.&nbsp;<\/span><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"900\" height=\"611\" data-src=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/97d495ea-4402-48c2-ba2d-08c28adf3cb1_dh-what-is-ux-7-1.jpg.webp\" alt=\"Resultados de la p\u00e1gina de PageSpeed de Google.\" class=\"wp-image-26715 lazyload\" data-srcset=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/97d495ea-4402-48c2-ba2d-08c28adf3cb1_dh-what-is-ux-7-1.jpg.webp 900w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2020\/09\/97d495ea-4402-48c2-ba2d-08c28adf3cb1_dh-what-is-ux-7-1-300x204.jpg 300w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2020\/09\/97d495ea-4402-48c2-ba2d-08c28adf3cb1_dh-what-is-ux-7-1-768x521.jpg 768w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/97d495ea-4402-48c2-ba2d-08c28adf3cb1_dh-what-is-ux-7-1-600x407.jpg.webp 600w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/97d495ea-4402-48c2-ba2d-08c28adf3cb1_dh-what-is-ux-7-1-730x496.jpg.webp 730w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/97d495ea-4402-48c2-ba2d-08c28adf3cb1_dh-what-is-ux-7-1-784x532.jpg.webp 784w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/97d495ea-4402-48c2-ba2d-08c28adf3cb1_dh-what-is-ux-7-1-877x595.jpg.webp 877w\" data-sizes=\"(max-width: 900px) 100vw, 900px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 900px; --smush-placeholder-aspect-ratio: 900\/611;\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Finalmente, el <\/span><a href=\"https:\/\/www.dreamhost.com\/blog\/es\/optimiza-velocidad-sitio-web\/\"><span style=\"font-weight: 400;\">rendimiento importa<\/span><\/a><span style=\"font-weight: 400;\"> para el UX. Las p\u00e1ginas lentas permiten que<\/span><a href=\"https:\/\/www.quicksprout.com\/website-speed\/\"><span style=\"font-weight: 400;\"> tus visitantes se vayan<\/span><\/a><span style=\"font-weight: 400;\"> antes de que el sitio tenga la oportunidad de cargar. Hay muchas formas de acelerar tu sitio, aunque tu mejor apuesta es <\/span><a href=\"https:\/\/www.dreamhost.com\/es\/hosting\/\"><span style=\"font-weight: 400;\">empezar con alojamiento de calidad<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n\n\n\n\n<div\n\tclass=\"article-cta-shared article-cta-small\"\n>\n    <div class=\"tr-img-wrap-outer jsLoading\"><img decoding=\"async\" class=\"js-img-lazy \" src=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/themes\/blog2018\/assets\/img\/lazy-loading-transparent.webp\" data-srcset=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/themes\/blog2018\/assets\/img\/article-small-ad-cta-placeholder.webp 1x, https:\/\/www.dreamhost.com\/blog\/wp-content\/themes\/blog2018\/assets\/img\/article-small-ad-cta-placeholder-x2.webp 2x\"  alt=\"Ad background image\" \/><\/div>\n\n\n\n\n  <div class=\"content-btm\">\n    <h2\n      class=\"h2--md\"\n    >\n      \u00bfEst\u00e1s construyendo una mejor experiencia de usuario?\n    <\/h2>\n    <p\n      class=\"p--md\"\n    >\n      Asociate con DreamHost. Nos aseguraremos de que tu sitio sea r\u00e1pido, seguro, y que siempre est\u00e9 en l\u00ednea para que tus visitantes conf\u00eden en ti. Planes desde $2.95 USD\/mes\n    <\/p>\n\n            <a\n            href=\"https:\/\/www.dreamhost.com\/es\/hosting\/\"\n                        class=\"btn btn--white-outline btn--sm btn--round\"\n                                    target=\"_blank\"\n            rel=\"noopener noreferrer\"\n            >\n                            Escoge tu plan                    <\/a>\n\n  <\/div>\n<\/div>\n\n\n<h2 id=\"h-recursos-ux\" class=\"wp-block-heading\"><b><a id=\"recursos-UX\"><\/a>Recursos UX<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">En este punto, es posible que hayas descifrado que un dise\u00f1o UX no es algo que puedas optimizar de una sola vez. Hay mucho m\u00e1s en este campo de lo que podemos cubrir en un art\u00edculo.<\/span><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"900\" height=\"476\" data-src=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/30b88ca7-c692-4741-b779-c00397bbd7ed_dh-what-is-ux-6-1.jpg.webp\" alt=\"P\u00e1gina de inicio de UX Matters, la cual usa un infogr\u00e1fico para navegar.\" class=\"wp-image-26721 lazyload\" data-srcset=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/30b88ca7-c692-4741-b779-c00397bbd7ed_dh-what-is-ux-6-1.jpg.webp 900w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2020\/09\/30b88ca7-c692-4741-b779-c00397bbd7ed_dh-what-is-ux-6-1-300x159.jpg 300w, https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2020\/09\/30b88ca7-c692-4741-b779-c00397bbd7ed_dh-what-is-ux-6-1-768x406.jpg 768w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/30b88ca7-c692-4741-b779-c00397bbd7ed_dh-what-is-ux-6-1-600x317.jpg.webp 600w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/30b88ca7-c692-4741-b779-c00397bbd7ed_dh-what-is-ux-6-1-730x386.jpg.webp 730w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/30b88ca7-c692-4741-b779-c00397bbd7ed_dh-what-is-ux-6-1-784x415.jpg.webp 784w, https:\/\/www.dreamhost.com\/blog\/wp-content\/smush-webp\/2020\/09\/30b88ca7-c692-4741-b779-c00397bbd7ed_dh-what-is-ux-6-1-877x464.jpg.webp 877w\" data-sizes=\"(max-width: 900px) 100vw, 900px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 900px; --smush-placeholder-aspect-ratio: 900\/476;\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Afortunadamente, hay muchos recursos UX de calidad a los que te puedes referir a medida que mejoras tu sitio web:&nbsp;<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">Awwwards es donde puedes encontrar inspiraci\u00f3n. Trae caf\u00e9; vas a estar navegando en esta p\u00e1gina por un buen rato.\u00a0<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">UXmatters cubre casi todo lo relacionado con el dise\u00f1o. Hay contenido para todos &#8211; desde un estratega de UX con experiencia, investigador UX, dise\u00f1ador de UI, o dise\u00f1ador gr\u00e1fico, hasta nuevos entusiastas de UX.<\/span><\/li>\n\n\n\n<li><i><span style=\"font-weight: 400;\">UX Magazine<\/span><\/i><span style=\"font-weight: 400;\"> publica las \u00faltimas noticias, perspectivas, e investigaciones de UX para cualquiera que est\u00e9 interesado en mejorar la experiencia digital de sus visitantes.<\/span><\/li>\n\n\n\n<li><i><span style=\"font-weight: 400;\">Stack Overflow<\/span><\/i><span style=\"font-weight: 400;\"> es el lugar para todas tus preguntas importantes. Es una comunidad abierta de personas serviciales y con mucho conocimiento.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">El <\/span><i><span style=\"font-weight: 400;\">Website and Digital Marketing Help<\/span><\/i><span style=\"font-weight: 400;\"> es un grupo de Facebook impulsado por DreamHost donde los due\u00f1os de sitios web de todos los niveles pueden compartir las mejores pr\u00e1cticas e ideas.\u00a0<\/span><\/li>\n\n\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Si combinas estos recursos con investigaci\u00f3n y pr\u00e1ctica, deber\u00e1s encontrarte a ti mismo implementado las buenas pr\u00e1cticas de experiencia de usuario en poco tiempo.<\/span><\/p>\n\n\n\n<h2 id=\"h-disenas-una-gran-experiencia-de-usuario\" class=\"wp-block-heading\"><b>Dise\u00f1as una gran experiencia de usuario<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">No necesitas ser un dise\u00f1ador profesional de UX para construir un sitio web con el que tu audiencia amar\u00e1 interactuar. Solo toma entender un poco lo que le har\u00e1 la vida m\u00e1s f\u00e1cil para tus visitantes y disponibilidad para construir un sitio que provea esa experiencia.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">El UX describe lo que es la experiencia de interactuar con tu sitio web para tus usuarios. Optimizar el UX de tu sitio significa asegurar que tiene navegaci\u00f3n clara, creando contenido que es f\u00e1cil de escanear, probando la sensibilidad&nbsp; y m\u00e1s. Hay mucho que aprender, pero tambi\u00e9n hay muchos recursos \u00fatiles y dise\u00f1adores con mucho conocimiento que pueden ayudar.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">\u00a1Despu\u00e9s de eso, vas a estar listo para conquistar el internet con tu sitio web optimizado para UX! Puedes revisar algunas de las tareas relacionadas con el rendimiento de tu lista temprano con nuestros planes de <\/span><a href=\"https:\/\/www.dreamhost.com\/es\/hosting\/\"><span style=\"font-weight: 400;\">Shared Website hosting<\/span><\/a><span style=\"font-weight: 400;\"> de alta calidad. <\/span><\/p>\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Qu\u00e9 momento para estar vivo! Los principiantes sin experiencia en c\u00f3digo ahora pueden construir un sitio con un esfuerzo y gastos m\u00ednimos. A\u00fan mejor, las opciones son infinitas: tienes un arsenal entero de colores, fuentes, im\u00e1genes, y botones a tu disposici\u00f3n. Pero con tantos elementos de dise\u00f1o para jugar, puede ser tentador volverse un poco [&hellip;]<\/p>\n","protected":false},"author":1060,"featured_media":25775,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_opengraph-title":"","_yoast_wpseo_opengraph-description":"","_yoast_wpseo_twitter-title":"","_yoast_wpseo_twitter-description":"","toc_headlines":"[[\"h-una-introduccion-a-la-experiencia-de-usuario-ux-y-por-que-es-importante\",\"Una introducci\u00f3n a la Experiencia de Usuario (UX) y por qu\u00e9 es importante\"],[\"h-el-papel-del-disenador-ux\",\"El papel del dise\u00f1ador UX\"],[\"h-como-reconocer-un-buen-diseno-ux\",\"C\u00f3mo reconocer un buen dise\u00f1o UX\"],[\"h-como-usar-ux-para-disenar-un-sitio-para-tu-audiencia\",\"C\u00f3mo usar UX para dise\u00f1ar un sitio para tu audiencia\"],[\"h-recursos-ux\",\"Recursos UX\"],[\"h-disenas-una-gran-experiencia-de-usuario\",\"Dise\u00f1as una gran experiencia de usuario\"]]","hide_toc":false,"show_updated_at":"0","footnotes":""},"categories":[11681,11668],"tags":[],"class_list":["post-26678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shared-hosting","category-tutoriales"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.3 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00bfQu\u00e9 es la experiencia de usuario? Consejos - DreamHost<\/title>\n<meta name=\"description\" content=\"Parece contradictorio, pero tu sitio web no est\u00e1 hecho para ti. Aprende c\u00f3mo construir el sitio \u00f3ptimo para tu audiencia objetiva con un buen dise\u00f1o UX\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dreamhost.com\/blog\/es\/que-es-experiencia-de-usuario\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es la experiencia de usuario ?\u00bfY c\u00f3mo usarla para crear un sitio ajustado a tu audiencia?\" \/>\n<meta property=\"og:description\" content=\"Parece contradictorio, pero tu sitio web no est\u00e1 hecho para ti. Aprende c\u00f3mo construir el sitio \u00f3ptimo para tu audiencia objetiva con un buen dise\u00f1o UX\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dreamhost.com\/blog\/es\/que-es-experiencia-de-usuario\/\" \/>\n<meta property=\"og:site_name\" content=\"DreamHost Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DreamHost\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-04T14:00:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-16T21:15:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2020\/09\/578a8078-7cc1-4d1c-aa1e-46633db813fe_what20is20ux20design20opt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"598\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Brian Glassman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@dreamhost\" \/>\n<meta name=\"twitter:site\" content=\"@dreamhost\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Brian Glassman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es la experiencia de usuario? Consejos - DreamHost","description":"Parece contradictorio, pero tu sitio web no est\u00e1 hecho para ti. Aprende c\u00f3mo construir el sitio \u00f3ptimo para tu audiencia objetiva con un buen dise\u00f1o UX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dreamhost.com\/blog\/es\/que-es-experiencia-de-usuario\/","og_locale":"en_US","og_type":"article","og_title":"\u00bfQu\u00e9 es la experiencia de usuario ?\u00bfY c\u00f3mo usarla para crear un sitio ajustado a tu audiencia?","og_description":"Parece contradictorio, pero tu sitio web no est\u00e1 hecho para ti. Aprende c\u00f3mo construir el sitio \u00f3ptimo para tu audiencia objetiva con un buen dise\u00f1o UX","og_url":"https:\/\/www.dreamhost.com\/blog\/es\/que-es-experiencia-de-usuario\/","og_site_name":"DreamHost Blog","article_publisher":"https:\/\/www.facebook.com\/DreamHost\/","article_published_time":"2020-09-04T14:00:45+00:00","article_modified_time":"2025-01-16T21:15:41+00:00","og_image":[{"width":900,"height":598,"url":"https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2020\/09\/578a8078-7cc1-4d1c-aa1e-46633db813fe_what20is20ux20design20opt.jpg","type":"image\/jpeg"}],"author":"Brian Glassman","twitter_card":"summary_large_image","twitter_creator":"@dreamhost","twitter_site":"@dreamhost","twitter_misc":{"Written by":"Brian Glassman","Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.dreamhost.com\/blog\/es\/que-es-experiencia-de-usuario\/#article","isPartOf":{"@id":"https:\/\/www.dreamhost.com\/blog\/es\/que-es-experiencia-de-usuario\/"},"author":{"name":"Brian Glassman","@id":"https:\/\/www.dreamhost.com\/blog\/#\/schema\/person\/e25c31f16fee80576bdd8b93a066f3de"},"headline":"\u00bfQu\u00e9 es la experiencia de usuario ?\u00bfY c\u00f3mo usarla para crear un sitio ajustado a tu audiencia?","datePublished":"2020-09-04T14:00:45+00:00","dateModified":"2025-01-16T21:15:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.dreamhost.com\/blog\/es\/que-es-experiencia-de-usuario\/"},"wordCount":2380,"publisher":{"@id":"https:\/\/www.dreamhost.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.dreamhost.com\/blog\/es\/que-es-experiencia-de-usuario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2020\/09\/578a8078-7cc1-4d1c-aa1e-46633db813fe_what20is20ux20design20opt.jpg","articleSection":["Shared Hosting","Tutoriales"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.dreamhost.com\/blog\/es\/que-es-experiencia-de-usuario\/","url":"https:\/\/www.dreamhost.com\/blog\/es\/que-es-experiencia-de-usuario\/","name":"\u00bfQu\u00e9 es la experiencia de usuario? Consejos - DreamHost","isPartOf":{"@id":"https:\/\/www.dreamhost.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dreamhost.com\/blog\/es\/que-es-experiencia-de-usuario\/#primaryimage"},"image":{"@id":"https:\/\/www.dreamhost.com\/blog\/es\/que-es-experiencia-de-usuario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2020\/09\/578a8078-7cc1-4d1c-aa1e-46633db813fe_what20is20ux20design20opt.jpg","datePublished":"2020-09-04T14:00:45+00:00","dateModified":"2025-01-16T21:15:41+00:00","description":"Parece contradictorio, pero tu sitio web no est\u00e1 hecho para ti. Aprende c\u00f3mo construir el sitio \u00f3ptimo para tu audiencia objetiva con un buen dise\u00f1o UX","breadcrumb":{"@id":"https:\/\/www.dreamhost.com\/blog\/es\/que-es-experiencia-de-usuario\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dreamhost.com\/blog\/es\/que-es-experiencia-de-usuario\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dreamhost.com\/blog\/es\/que-es-experiencia-de-usuario\/#primaryimage","url":"https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2020\/09\/578a8078-7cc1-4d1c-aa1e-46633db813fe_what20is20ux20design20opt.jpg","contentUrl":"https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2020\/09\/578a8078-7cc1-4d1c-aa1e-46633db813fe_what20is20ux20design20opt.jpg","width":900,"height":598},{"@type":"BreadcrumbList","@id":"https:\/\/www.dreamhost.com\/blog\/es\/que-es-experiencia-de-usuario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dreamhost.com\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 es la experiencia de usuario ?\u00bfY c\u00f3mo usarla para crear un sitio ajustado a tu audiencia?"}]},{"@type":"WebSite","@id":"https:\/\/www.dreamhost.com\/blog\/#website","url":"https:\/\/www.dreamhost.com\/blog\/","name":"DreamHost Blog","description":"","publisher":{"@id":"https:\/\/www.dreamhost.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dreamhost.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.dreamhost.com\/blog\/#organization","name":"DreamHost","url":"https:\/\/www.dreamhost.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dreamhost.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhblog.dream.press\/blog\/wp-content\/uploads\/2019\/01\/dh_logo-blue-2.png","contentUrl":"https:\/\/dhblog.dream.press\/blog\/wp-content\/uploads\/2019\/01\/dh_logo-blue-2.png","width":1200,"height":168,"caption":"DreamHost"},"image":{"@id":"https:\/\/www.dreamhost.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DreamHost\/","https:\/\/x.com\/dreamhost","https:\/\/www.instagram.com\/dreamhost\/","https:\/\/www.linkedin.com\/company\/dreamhost\/","https:\/\/www.youtube.com\/user\/dreamhostusa"]},{"@type":"Person","@id":"https:\/\/www.dreamhost.com\/blog\/#\/schema\/person\/e25c31f16fee80576bdd8b93a066f3de","name":"Brian Glassman","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2022\/01\/brian-glassman-dreamhost-150x150.jpg","url":"https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2022\/01\/brian-glassman-dreamhost-150x150.jpg","contentUrl":"https:\/\/www.dreamhost.com\/blog\/wp-content\/uploads\/2022\/01\/brian-glassman-dreamhost-150x150.jpg","caption":"Brian Glassman"},"description":"SEO leader and content marketer, Brian is DreamHost\u2019s Director of SEO. Based in Chicago, Brian enjoys the local health food scene (deep dish pizza, Italian beef sandwiches) and famous year-round warm weather. Follow Brian on LinkedIn.","sameAs":["https:\/\/www.linkedin.com\/in\/brianglassmandesign\/"],"url":"https:\/\/www.dreamhost.com\/blog\/author\/brian\/"}]}},"lang":"es","translations":{"es":26678,"en":25767,"de":51996,"pl":52000,"ru":54181,"uk":54186,"pt":54210,"it":69057,"fr":71696,"nl":71726},"pll_sync_post":{},"_links":{"self":[{"href":"https:\/\/www.dreamhost.com\/blog\/wp-json\/wp\/v2\/posts\/26678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dreamhost.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dreamhost.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dreamhost.com\/blog\/wp-json\/wp\/v2\/users\/1060"}],"version-history":[{"count":10,"href":"https:\/\/www.dreamhost.com\/blog\/wp-json\/wp\/v2\/posts\/26678\/revisions"}],"predecessor-version":[{"id":63317,"href":"https:\/\/www.dreamhost.com\/blog\/wp-json\/wp\/v2\/posts\/26678\/revisions\/63317"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dreamhost.com\/blog\/wp-json\/wp\/v2\/media\/25775"}],"wp:attachment":[{"href":"https:\/\/www.dreamhost.com\/blog\/wp-json\/wp\/v2\/media?parent=26678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dreamhost.com\/blog\/wp-json\/wp\/v2\/categories?post=26678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dreamhost.com\/blog\/wp-json\/wp\/v2\/tags?post=26678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}